{"id":1294,"date":"2018-10-02T09:17:40","date_gmt":"2018-10-02T12:17:40","guid":{"rendered":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/?page_id=1294"},"modified":"2018-10-02T09:18:57","modified_gmt":"2018-10-02T12:18:57","slug":"rede-credenciada-piaui","status":"publish","type":"page","link":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/rede-credenciada-piaui\/","title":{"rendered":"Rede Credenciada Piau\u00ed"},"content":{"rendered":"  <div id=\"page-header-926759005\" class=\"page-header-wrapper\">\n  <div class=\"page-title dark featured-title\">\n\n    \n    <div class=\"page-title-inner container align-center flex-row medium-flex-wrap\" >\n              <div class=\"title-wrapper flex-col text-left medium-text-center\">\n          <h1 class=\"entry-title mb-0\">\n            Rede Credenciada Piau\u00ed          <\/h1>\n        <\/div>\n                    <div class=\"title-content flex-col flex-right text-right medium-text-center\">\n        <div class=\"title-breadcrumbs pb-half pt-half\"><\/div>      <\/div>\n    <\/div>\n\n       <\/div>\n    <\/div>\n  \n\t<div id=\"gap-1196180571\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1196180571 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-884581756\">\n\n\t<div id=\"col-1944789178\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1184 size-large\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/rede-credenciada-bradesco-sa\u00fade-1024x437.jpg\" alt=\"\" width=\"1020\" height=\"435\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/rede-credenciada-bradesco-sa\u00fade-1024x437.jpg 1024w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/rede-credenciada-bradesco-sa\u00fade-300x128.jpg 300w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/rede-credenciada-bradesco-sa\u00fade-768x328.jpg 768w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/rede-credenciada-bradesco-sa\u00fade.jpg 1920w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p>O Bradesco Sa\u00fade oferece os melhores hospitais, laborat\u00f3rios e m\u00e9dicos do Brasil. O desempenho de uma grande seguradora como a Bradesco Sa\u00fade \u00e9 visto com sucesso n\u00e3o somente com a cura de doen\u00e7as, mas sim quando a seguradora trabalha junto com o seu segurado para evitar que problemas de sa\u00fade eventualmente ocorram. O Bradesco Sa\u00fade trabalha dessa maneira, o que lhe rendeu credibilidade e confian\u00e7a ao longo de sua trajet\u00f3ria no mercado de seguro sa\u00fade.<\/p>\n<p>A Rede do <strong><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/bradesco-saude\/bradesco-saude-piaui\/\" target=\"_blank\" rel=\"noopener\">Bradesco Sa\u00fade Piau\u00ed<\/a><\/strong> vai al\u00e9m de nomes de hospitais renomados, profissionais e laborat\u00f3rios de alta qualidade, Com o objetivo de sempre facilitar o dia a dia dos seus segurados, a Bradesco Sa\u00fade disponibilizou para download a vers\u00e3o atualizada do seu aplicativo, oferecendo novas funcionalidades, tais como: consultar reembolso, localizar referenciados, visualizar o cart\u00e3o de identifica\u00e7\u00e3o online \u2013 por interm\u00e9dio do aplicativo Carteira Digital, localizar farm\u00e1cias pr\u00f3ximas, 2\u00aa via do extrato de IR, al\u00e9m de criar a carteira de vacina\u00e7\u00e3o e acessar o calend\u00e1rio de vacinas.<\/p>\n<p>Para utilizar o aplicativo, o segurado precisa baix\u00e1-lo por meio do Google Play (plataforma Android) ou a App Store (iOS) de seu smatphone, para baixar o aplicativo Bradesco sa\u00fade\u00a0<strong><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=br.com.bradseg.segurobradescosaude&amp;hl=pt_BR\" target=\"_blank\" rel=\"noopener\">CLIQUE AQUI<\/a><\/strong><\/p>\n<h2><strong><span style=\"color: #3366ff;\">Bradesco Rede Credenciada Piau\u00ed<\/span><\/strong><\/h2>\n<table class=\"static small ta-c\">\n<tbody>\n<tr class=\"bgGray\">\n<td class=\"ta-c\" colspan=\"3\"><span style=\"color: #ed1c24;\"><strong><span class=\"fz-11\">FLEX<\/span><\/strong><\/span><\/td>\n<\/tr>\n<tr class=\"bgGray\">\n<td class=\"ta-l\" colspan=\"3\"><strong>Hospitais<\/strong>\u00a0(13)<\/td>\n<\/tr>\n<tr>\n<td class=\"ta-l va-t\" colspan=\"1\">\n<div class=\"fz-7\"><strong>Teresina \u2013 Zona Central<\/strong><br \/>\nCOT \u2013 H<br \/>\nHOSPITAL FLAVIO SANTOS \u2013 H\/ PS<br \/>\nITA COR \u2013 H<br \/>\nPRONTO MED ADULTO \u2013 H\/ PS<br \/>\nPRONTO MED PEDIATRICO \u2013 H\/ PS<\/div>\n<\/td>\n<td class=\"ta-l va-t\" colspan=\"1\">\n<div class=\"fz-7\"><strong>Parna\u00edba \u2013 Zona Central<\/strong><br \/>\nMATERNIDADE MARQUES BASTOS \u2013 H\/ PS<br \/>\nPRO MEDICA \u2013 H<br \/>\n<strong>Picos \u2013 Zona Central<\/strong><br \/>\nHOSPITAL MEMORIAL DO CARMO \u2013 H\/ M\/ PS<br \/>\n<strong>Floriano \u2013 Zona Central<\/strong><br \/>\nCLINICOR \u2013 H<\/div>\n<\/td>\n<td class=\"ta-l va-t\" colspan=\"1\">\n<div class=\"fz-7\">HOSPITAL JOAO PAULO II \u2013 H<br \/>\n<strong>Teresina \u2013 Outras Regi\u00f5es<\/strong><br \/>\nCL\u00cdNICA SANTA F\u00c9 LTDA. \u2013 H\/ M<br \/>\nHOSPITAL SAO PAULO \u2013 H\/ PS<br \/>\nHOSP. SANTA MARIA \u2013 H\/ PS<\/div>\n<\/td>\n<\/tr>\n<tr class=\"bgGray\">\n<td class=\"ta-c\" colspan=\"3\"><span style=\"color: #ed1c24;\"><strong><span class=\"fz-11\">TNE<\/span>\u00a0(+ FLEX)<\/strong><\/span><\/td>\n<\/tr>\n<tr class=\"bgGray\">\n<td class=\"ta-l\" colspan=\"3\"><strong>Hospitais<\/strong>\u00a0(8)<\/td>\n<\/tr>\n<tr>\n<td class=\"ta-l va-t\" colspan=\"1\">\n<div class=\"fz-7\"><strong>Teresina \u2013 Zona Central<\/strong><br \/>\nCL. DE ACIDENTADOS SAO LUCAS \u2013 H\/ PS<br \/>\nCOT \u2013 PS<br \/>\nITA COR \u2013 PS<\/div>\n<\/td>\n<td class=\"ta-l va-t\" colspan=\"1\">\n<div class=\"fz-7\"><strong>Floriano \u2013 Zona Central<\/strong><br \/>\nCLINICOR \u2013 H<br \/>\nHOSPITAL JOAO PAULO II \u2013 PS<br \/>\n<strong>Teresina \u2013 Outras Regi\u00f5es<\/strong><br \/>\nCASA DE SAUDE MAT. TERESINA \u2013 H\/ M\/ PS<\/div>\n<\/td>\n<td class=\"ta-l va-t\" colspan=\"1\">\n<div class=\"fz-7\">HOSPITAL S\u00c3O PEDRO \u2013 H<br \/>\n<strong>Parna\u00edba \u2013 Outras Regi\u00f5es<\/strong><br \/>\nCASA SA\u00daDE MAT. N.S. F\u00c1TIMA LTDA. \u2013 H<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"static small\">\n<tbody>\n<tr class=\"bgGray\">\n<td class=\"ta-l\"><strong><span style=\"color: #ed1c24;\">Legendas<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"ta-l\">H \u2013 Interna\u00e7\u00e3o Eletiva, M \u2013 Maternidade, PS \u2013 Pronto Socorro<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 120%;\">Preencha o formul\u00e1rio abaixo e receba todas as informa\u00e7\u00f5es como tabela de valores, rede credenciada car\u00eancias e outras informa\u00e7\u00f5es importantes.<\/span><\/p>\n<div data-uniq='6a04de5859a98' class='uniq-6a04de5859a98 formcraft-css form-live align-left'><style type='text\/css' scoped='scoped'>.zopim { display:none !important;}\n.heading-cover  { DISPLAY:NONE !IMPORTANT;}\nhtml .formcraft-css .fc-form .form-element .form-element-html {\n    padding: 1.5em 1.5em;\n    padding-left: 0;\n    padding-top: 0;\n    margin-top: -10px;\nbackground:transparent !important;\n}\nhtml .formcraft-css .fc-form .field-cover>span>span {\n    display: block;\n    width: 100%;\n    line-height: 1.45em;\n    font-weight: 600;\n    font-size: 17px;\n}\n.select2-container.select2-container--default .select2-selection--single {\n    -webkit-border-radius: 0;\n    -moz-border-radius: 0;\n    -ms-border-radius: 0;\n    border-radius: 0;\n    border: 1px solid #cacaca;\n    height: 40px;\n    line-height: 1;\n    background: #fafafa;\n    font-size: 13px;\n}\n.select2-container.select2-container--default .select2-selection--single .select2-selection__rendered {\n    line-height: 43px;\n    padding-left: 11px;\n    padding-right: 50px;\n    color: #222222;\n    text-transform: uppercase;\n}<\/style><div class='form-logic'>[[[[\"field36\",\"equal_to\",\"Sim\"]],[[\"show_fields\",\"field32\"]],\"and\"]]<\/div><div class=\"fc-pagination-cover fc-pagination-1\">\n\t\t\t\t<div class=\"fc-pagination width-100\">\n\t\t\t\t\t<div class=\"pagination-trigger \" data-index=\"0\">\n\t\t\t\t\t\t<span class=\"page-number\"><span >1<\/span><\/span>\n\t\t\t\t\t\t<span class=\"page-name \">Step 1<\/span>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t<style scoped=\"scoped\" >\n\t\t\t@media (max-width : 480px) {\n\t\t\t\t.fc_modal-dialog-1 .fc-pagination-cover .fc-pagination\n\t\t\t\t{\n\t\t\t\t\tbackground-color: transparent !important;\n\t\t\t\t}\n\t\t\t}\n\t\t\t\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .submit-cover .submit-button,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .fileupload-cover .button-file,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover .button,\n\t\t\t.formcraft-datepicker .ui-datepicker-header,\n\t\t\t.formcraft-datepicker .ui-datepicker-title\n\t\t\t{\n\t\t\t\tbackground: #d83135;\n\t\t\t\tcolor: #ffffff;\n\t\t\t}\n\t\t\t.formcraft-datepicker td .ui-state-active,\n\t\t\t.formcraft-datepicker td .ui-state-hover,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .slider-cover .ui-slider-range\n\t\t\t{\n\t\t\t\tbackground: #d83135;\n\t\t\t}\n\t\t\t#ui-datepicker-div.formcraft-datepicker .ui-datepicker-header,\n\t\t\t.formcraft-css .fc-form .field-cover>div.full hr\n\t\t\t{\n\t\t\t\tborder-color: #be2b2e;\n\t\t\t}\n\t\t\t#ui-datepicker-div.formcraft-datepicker .ui-datepicker-prev:hover,\n\t\t\t#ui-datepicker-div.formcraft-datepicker .ui-datepicker-next:hover,\n\t\t\t#ui-datepicker-div.formcraft-datepicker select.ui-datepicker-month:hover,\n\t\t\t#ui-datepicker-div.formcraft-datepicker select.ui-datepicker-year:hover\n\t\t\t{\n\t\t\t\tbackground-color: #be2b2e;\n\t\t\t}\n\t\t\t.formcraft-css .fc-pagination>div.active .page-number,\n\t\t\t.formcraft-css .form-cover-builder .fc-pagination>div:first-child .page-number\n\t\t\t{\n\t\t\t\tbackground-color: #d83135;\n\t\t\t\tcolor: #ffffff;\n\t\t\t}\n\t\t\t#ui-datepicker-div.formcraft-datepicker table.ui-datepicker-calendar th,\n\t\t\t#ui-datepicker-div.formcraft-datepicker table.ui-datepicker-calendar td.ui-datepicker-today a,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .star-cover label,\n\t\t\thtml .formcraft-css .fc-form.label-floating .form-element .field-cover.has-focus>span,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .customText-cover a,\n\t\t\t.formcraft-css .prev-next>div span:hover\n\t\t\t{\n\t\t\t\tcolor: #d83135;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .customText-cover a:hover\n\t\t\t{\n\t\t\t\tcolor: #be2b2e;\n\t\t\t}\n\t\t\thtml .formcraft-css .fc-form.fc-form-1.label-floating .form-element .field-cover > span\n\t\t\t{\n\t\t\t\tcolor: #666666;\n\t\t\t}\n\t\t\thtml .formcraft-css .fc-form .final-success .final-success-check {\n\t\t\t\tborder: 2px solid #666666;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"text\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"email\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"password\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"tel\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover textarea,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover select,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover .time-fields-cover,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover .awesomplete ul\n\t\t\t{\n\t\t\t\tcolor: #777;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"text\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"password\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"email\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"radio\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"checkbox\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"tel\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover select,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover textarea\n\t\t\t{\n\t\t\t\tbackground-color: #fafafa;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"radio\"]:checked,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"checkbox\"]:checked {\n\t\t\t\tborder-color: #be2b2e;\n\t\t\t\tbackground: #d83135;\t\t\t\t\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .star-cover label .star\n\t\t\t{\n\t\t\t\ttext-shadow: 0px 1px 0px #be2b2e;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .slider-cover .ui-slider-range\n\t\t\t{\n\t\t\t\tbox-shadow: 0px 1px 1px #be2b2e inset;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .fileupload-cover .button-file\n\t\t\t{\n\t\t\t\tborder-color: #be2b2e;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .form-element-html input[type=\"password\"]:focus,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .form-element-html input[type=\"email\"]:focus,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .form-element-html input[type=\"tel\"]:focus,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .form-element-html input[type=\"text\"]:focus,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .form-element-html textarea:focus,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .form-element-html select:focus\n\t\t\t{\n\t\t\t\tborder-color: #d83135;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .form-element-html .field-cover .is-read-only:focus {\n\t\t\t\tborder-color: #ccc;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1\t\t\t{\n\t\t\t\tfont-family: inherit;\n\t\t\t}\n\t\t\t@media (max-width : 480px) {\n\t\t\t\thtml .dedicated-page,\n\t\t\t\thtml .dedicated-page .formcraft-css .fc-pagination > div.active\n\t\t\t\t{\n\t\t\t\t\tbackground: transparent;\n\t\t\t\t}\n\t\t\t}\n\t\t<\/style>\n\t\t<div class=\"form-cover\">\n\t\t\t<form data-auto-scroll=\"\" data-no-message-redirect=\"\" data-thousand=\"\" data-decimal=\".\" data-delay=\"\" data-id=\"1\" class=\"fc-form fc-form-1 align- fc-temp-class spin- save-form- dont-submit-hidden- remove-asterisk- disable-enter- label-placeholder field-border-visible frame-visible icons-hide-false field-alignment-left\" style=\"width: 100%; color: #666666; font-size: 100%; background: transparent\">\n\t\t\t\t<div class=\"form-page form-page-0\" data-index=\"0\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"form-page-content     \">\n\t\t\t\t\t\t<div data-identifier=\"field41\" data-index=\"0\" style=\"width: 100%\" class=\" form-element form-element-field41 options- index- form-element-0 default-false form-element-type-heading is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><div style=\"background-color:\" class=\"heading-cover field-cover \"><div style=\"text-align: left; font-size: 1.5em; padding-top: ; padding-bottom: ; color:\" class=\"bold-\"><span >BRADESCO<\/span><\/div><input type=\"hidden\" data-field-id=\"field41\" name=\"field41[]\" value=\"BRADESCO\"><\/div><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field1\" data-index=\"1\" style=\"width: 50%\" class=\" even form-element form-element-field1 options- index- form-element-1 default-false form-element-type-oneLineText is-required-true -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >Nome para Contato<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"Nome para Contato\" make-read-only=\"\" data-field-id=\"field1\" name=\"field1[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"\" data-regexp=\"\" data-is-required=\"true\" data-allow-spaces=\"true\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-icon-user\">icon-user<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field37\" data-index=\"2\" style=\"width: 50%\" class=\" form-element form-element-field37 options- index- form-element-2 default-false form-element-type-dropdown is-required-true odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"dropdown-cover field-cover autocomplete-type- \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >Voc\u00ea possui?<\/span><\/span><span class=\"sub-label\"><span >pick one!<\/span><\/span><\/span><div><span class=\"error\"><\/span><select data-is-required=\"true\" class=\"validation-lenient\" data-field-id=\"field37\" name=\"field37\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"hover\" data-html=\"true\" data-original-title=\"\"><option value=\"\" class=\" \">Possui CNPJ?<\/option><option value=\"Sim\" class=\" \">Sim<\/option><option value=\"N\u00e3o\" class=\" \">N\u00e3o<\/option><\/select><input type=\"text\"><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field3\" data-index=\"3\" style=\"width: 100%\" class=\" even form-element form-element-field3 options- index- form-element-3 default-false form-element-type-email is-required-true -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"email-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >E-mail<\/span><\/span><span class=\"sub-label\"><span >a valid email<\/span><\/span><\/span><div><span class=\"error\"><\/span><input placeholder=\"E-mail\" data-field-id=\"field3\" type=\"text\" data-val-type=\"email\" make-read-only=\"\" data-is-required=\"true\" name=\"field3\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-original-title=\"\"><i class=\"formcraft-icon\">email<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field21\" data-index=\"4\" style=\"width: 50%\" class=\" form-element form-element-field21 options- index- form-element-4 default-false form-element-type-oneLineText is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >Telefone<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"Telefone\" make-read-only=\"\" data-field-id=\"field21\" name=\"field21[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-icon-phone\">icon-phone<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field42\" data-index=\"5\" style=\"width: 50%\" class=\" even form-element form-element-field42 options- index- form-element-5 default-false form-element-type-oneLineText is-required-false -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >Celular<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"Celular\" make-read-only=\"\" data-field-id=\"field42\" name=\"field42[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-icon-phone\">icon-phone<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field38\" data-index=\"6\" style=\"width: 70%\" class=\" form-element form-element-field38 options- index- form-element-6 default-false form-element-type-oneLineText is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >Cidade<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"Cidade\" make-read-only=\"\" data-field-id=\"field38\" name=\"field38[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"true\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field40\" data-index=\"7\" style=\"width: 30%\" class=\" even form-element form-element-field40 options- index- form-element-7 default-false form-element-type-dropdown is-required-false -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"dropdown-cover field-cover autocomplete-type- \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >Estado<\/span><\/span><span class=\"sub-label\"><span >pick one!<\/span><\/span><\/span><div><span class=\"error\"><\/span><select data-is-required=\"false\" class=\"validation-lenient\" data-field-id=\"field40\" name=\"field40\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"hover\" data-html=\"true\" data-original-title=\"\"><option value=\"\" class=\" \">Estado<\/option><option value=\"AC\" class=\" \">AC<\/option><option value=\"AL\" class=\" \">AL<\/option><option value=\"AP\" class=\" \">AP<\/option><option value=\"AM\" class=\" \">AM<\/option><option value=\"BA\" class=\" \">BA<\/option><option value=\"CE\" class=\" \">CE<\/option><option value=\"DF\" class=\" \">DF<\/option><option value=\"ES\" class=\" \">ES<\/option><option value=\"GO\" class=\" \">GO<\/option><option value=\"MA\" class=\" \">MA<\/option><option value=\"MT\" class=\" \">MT<\/option><option value=\"MS\" class=\" \">MS<\/option><option value=\"MG\" class=\" \">MG<\/option><option value=\"PA\" class=\" \">PA<\/option><option value=\"PB\" class=\" \">PB<\/option><option value=\"PR\" class=\" \">PR<\/option><option value=\"PE\" class=\" \">PE<\/option><option value=\"PI\" class=\" \">PI<\/option><option value=\"RJ\" class=\" \">RJ<\/option><option value=\"RN\" class=\" \">RN<\/option><option value=\"RS\" class=\" \">RS<\/option><option value=\"RO\" class=\" \">RO<\/option><option value=\"RR\" class=\" \">RR<\/option><option value=\"SC\" class=\" \">SC<\/option><option value=\"SP\" class=\" \">SP<\/option><option value=\"SE\" class=\" \">SE<\/option><option value=\"TO\" class=\" \">TO<\/option><\/select><input type=\"text\"><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field20\" data-index=\"8\" style=\"width: 100%\" class=\" form-element form-element-field20 options- index- form-element-8 default-false form-element-type-customText is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><div class=\"absolute-false customText-cover field-cover\" style=\"left: ; top: ;right: ;bottom: ;color: #666666 !important; background-color:\"><div class=\"full\" style=\"text-align: left\"><p style=\"text-align: center\" >Insira a quantidade de usu\u00e1rios dentro de cada <b>faixa et\u00e1ria <\/b>abaixo.<\/p><\/div><input type=\"hidden\" name=\"field20\" data-field-id=\"field20\"><\/div><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field5\" data-index=\"9\" style=\"width: 33%\" class=\" even form-element form-element-field5 options- index- form-element-9 default-false form-element-type-oneLineText is-required-false -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >00-18<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"00-18\" make-read-only=\"\" data-field-id=\"field5\" name=\"field5[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field9\" data-index=\"10\" style=\"width: 34%\" class=\" form-element form-element-field9 options- index- form-element-10 default-false form-element-type-oneLineText is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >19-23<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"19-23\" make-read-only=\"\" data-field-id=\"field9\" name=\"field9[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field12\" data-index=\"11\" style=\"width: 33%\" class=\" even form-element form-element-field12 options- index- form-element-11 default-false form-element-type-oneLineText is-required-false -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >24-28<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"24-28\" make-read-only=\"\" data-field-id=\"field12\" name=\"field12[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field11\" data-index=\"12\" style=\"width: 33%\" class=\" form-element form-element-field11 options- index- form-element-12 default-false form-element-type-oneLineText is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >29-33<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"29-33\" make-read-only=\"\" data-field-id=\"field11\" name=\"field11[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field10\" data-index=\"13\" style=\"width: 34%\" class=\" even form-element form-element-field10 options- index- form-element-13 default-false form-element-type-oneLineText is-required-false -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >34-38<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"34-38\" make-read-only=\"\" data-field-id=\"field10\" name=\"field10[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field13\" data-index=\"14\" style=\"width: 33%\" class=\" form-element form-element-field13 options- index- form-element-14 default-false form-element-type-oneLineText is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >39-43<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"39-43\" make-read-only=\"\" data-field-id=\"field13\" name=\"field13[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field15\" data-index=\"15\" style=\"width: 33%\" class=\" even form-element form-element-field15 options- index- form-element-15 default-false form-element-type-oneLineText is-required-false -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >44-48<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"44-48\" make-read-only=\"\" data-field-id=\"field15\" name=\"field15[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field14\" data-index=\"16\" style=\"width: 34%\" class=\" form-element form-element-field14 options- index- form-element-16 default-false form-element-type-oneLineText is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >49-53<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"49-53\" make-read-only=\"\" data-field-id=\"field14\" name=\"field14[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field8\" data-index=\"17\" style=\"width: 33%\" class=\" even form-element form-element-field8 options- index- form-element-17 default-false form-element-type-oneLineText is-required-false -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >54-58<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"54-58\" make-read-only=\"\" data-field-id=\"field8\" name=\"field8[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field7\" data-index=\"18\" style=\"width: 33%\" class=\" form-element form-element-field7 options- index- form-element-18 default-false form-element-type-oneLineText is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >59+<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"59+\" make-read-only=\"\" data-field-id=\"field7\" name=\"field7[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field4\" data-index=\"19\" style=\"width: 67%\" class=\" even form-element form-element-field4 options- index- form-element-19 default-false form-element-type-submit is-required-false -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><div class=\"align-right wide-true submit-cover field-cover\"><button type=\"submit\" class=\"button submit-button\"><span class=\"text \">SOLICITAR OR\u00c7AMENTO<\/span><span class=\"spin-cover\"><i style=\"color:\" class=\"loading-icon icon-cog animate-spin\"><\/i><\/span><\/button><\/div><div class=\"submit-response \"><\/div><label ><input type=\"text\" class=\"required_field\" name=\"website\" autocomplete=\"maple-syrup-pot\"><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/form>\n\t\t\t<div class=\"prev-next prev-next-1\" style=\"width: 100%; color: #666666; font-size: 100%; background: transparent\">\n\t\t\t\t<div><label><input type=\"text\" class=\"  \"><\/label><span class=\"inactive page-prev \"><i class=\"formcraft-icon\">keyboard_arrow_left<\/i>Previous<\/span><\/div>\n\t\t\t\t<div><label><input type=\"text\" class=\"  \"><\/label><span class=\"page-next \">Next<i class=\"formcraft-icon\">keyboard_arrow_right<\/i><\/span><\/div>\n\t\t\t<\/div>\n\t\t<\/div><a class=\"powered-by\" target=\"_blank\" href=\"http:\/\/formcraft-wp.com?source=pb\"\/>FormCraft - WordPress form builder<\/a><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:120%;\">PLANOS BRADESCO SA\u00daDE<\/span><b><\/b><\/h3><\/div>\n<div class=\"row row-box-shadow-3 row-box-shadow-5-hover\"  id=\"row-1944518580\">\n\n\t<div id=\"col-1873038449\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_270235291\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"306\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-empresarial-2.png\" class=\"attachment-large size-large\" alt=\"Bradesco Sa\u00fade empresarial\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-empresarial-2.png 500w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-empresarial-2-300x184.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_270235291 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_632882445\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_632882445 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1905443310\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_153209767\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"306\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-familiar-ades\u00e3o.png\" class=\"attachment-large size-large\" alt=\"Bradesco Sa\u00fade familiar ades\u00e3o\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-familiar-ades\u00e3o.png 500w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-familiar-ades\u00e3o-300x184.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_153209767 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_793295027\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_793295027 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2077916261\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_210091424\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"306\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-individual-Ades\u00e3o.png\" class=\"attachment-large size-large\" alt=\"Bradesco Sa\u00fade individual Ades\u00e3o\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-individual-Ades\u00e3o.png 500w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-individual-Ades\u00e3o-300x184.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_210091424 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1790904339\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1790904339 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1898127219\">\n\n\t<div id=\"col-860789309\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<h5 class=\"uppercase\"><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano\/empresarial\/\" target=\"_blank\" rel=\"noopener noreferrer\">Bradesco sa\u00fade empresarial<\/a><\/h5>\n<p>A Bradesco Sa\u00fade possui planos na medida certa para empresas que sabem que pensar em produtividade \u00e9, antes de tudo, pensar na qualidade de vida dos seus funcionarios.<\/p>\n<a rel=\"noopener noreferrer\" href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano\/empresarial\/\" target=\"_blank\" class=\"button primary is-smaller\"  >\n    <span>CONHE\u00c7A O PLANO<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-866397636\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<h5 class=\"uppercase\"><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano\/familiar\/\" target=\"_blank\" rel=\"noopener noreferrer\">bradesco sa\u00fade familiar<\/a><\/h5>\n<p>O plano de sa\u00fade Bradesco Familiar por ades\u00e3o \u00e9 um do mais bem vistos do pa\u00eds, isso porque conta com um excelente servi\u00e7o, uma rede credenciada com equipamentos de ponta.<\/p>\n<a rel=\"noopener noreferrer\" href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano\/familiar\/\" target=\"_blank\" class=\"button primary is-smaller\"  >\n    <span>CONHE\u00c7A O PLANO<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-100131897\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<h5 class=\"uppercase\"><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano\/por-adesao\/\" target=\"_blank\" rel=\"noopener noreferrer\">bradesco saude ades\u00e3o<\/a><\/h5>\n<p>Os planos de sa\u00fade Bradesco por ades\u00e3o possuem condi\u00e7\u00f5es especiais para diversas categorias profissionais. Aqui voc\u00ea conhece informa\u00e7\u00f5es completas sobre os planos.<\/p>\n<a rel=\"noopener noreferrer\" href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano\/por-adesao\/\" target=\"_blank\" class=\"button primary is-smaller\"  >\n    <span>CONHE\u00c7A O PLANO<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-1294","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rede Credenciada Piau\u00ed -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/rede-credenciada-piaui\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rede Credenciada Piau\u00ed -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/rede-credenciada-piaui\/\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-02T12:18:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/rede-credenciada-piaui\/\",\"url\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/rede-credenciada-piaui\/\",\"name\":\"Rede Credenciada Piau\u00ed -\",\"isPartOf\":{\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#website\"},\"datePublished\":\"2018-10-02T12:17:40+00:00\",\"dateModified\":\"2018-10-02T12:18:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/rede-credenciada-piaui\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/rede-credenciada-piaui\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/rede-credenciada-piaui\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rede Credenciada Piau\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#website\",\"url\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/\",\"name\":\"\",\"description\":\"Plano com 50% Desconto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rede Credenciada Piau\u00ed -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/rede-credenciada-piaui\/","og_locale":"pt_BR","og_type":"article","og_title":"Rede Credenciada Piau\u00ed -","og_url":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/rede-credenciada-piaui\/","article_modified_time":"2018-10-02T12:18:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/rede-credenciada-piaui\/","url":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/rede-credenciada-piaui\/","name":"Rede Credenciada Piau\u00ed -","isPartOf":{"@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#website"},"datePublished":"2018-10-02T12:17:40+00:00","dateModified":"2018-10-02T12:18:57+00:00","breadcrumb":{"@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/rede-credenciada-piaui\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/planodesaudebr.com.br\/bradesco-saude\/rede-credenciada-piaui\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/rede-credenciada-piaui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/"},{"@type":"ListItem","position":2,"name":"Rede Credenciada Piau\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#website","url":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/","name":"","description":"Plano com 50% Desconto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/pages\/1294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/comments?post=1294"}],"version-history":[{"count":2,"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/pages\/1294\/revisions"}],"predecessor-version":[{"id":1298,"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/pages\/1294\/revisions\/1298"}],"wp:attachment":[{"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/media?parent=1294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}