{"id":6921,"date":"2020-03-16T20:15:30","date_gmt":"2020-03-16T23:15:30","guid":{"rendered":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/?page_id=6921"},"modified":"2020-03-21T22:11:24","modified_gmt":"2020-03-22T01:11:24","slug":"plano-de-saude-bradesco","status":"publish","type":"page","link":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-de-saude-bradesco\/","title":{"rendered":"Plano de Sa\u00fade Bradesco"},"content":{"rendered":"\n  <div class=\"banner has-hover\" id=\"banner-1810079734\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-514373301\" class=\"text-box banner-layer x50 md-x50 lg-x50 y10 md-y10 lg-y10 res-text\">\n                                <div class=\"text dark\">\n              \n              <div class=\"text-inner text-left\">\n                  \n<h1><span style=\"font-size: 95%;\">Plano de Sa\u00fade Bradesco<\/span><\/h1>\n<p><span style=\"font-size: 140%;\">O <strong>Plano de Sa\u00fade Bradesco empresarial<\/strong> pode ser contratado por todos que possui uma empresa CNPJ ou MEI a partir de 3 pessoas sendo 1 titular e 2 dependentes.<\/span><\/p>\n<p><span style=\"font-size: 140%;\">Promo\u00e7\u00e3o Bradesco Sa\u00fade Empresarial, at\u00e9 50% de desconto na primeira mensalidade, Fale com um dos nossos corretores.<\/span><\/p>\n<a rel=\"noopener noreferrer\" href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/orcamento\/\" target=\"_blank\" class=\"button primary reveal-icon\"  style=\"border-radius:8px;\">\n    <span>Solicitar or\u00e7amento<\/span>\n  <i class=\"icon-checkmark\" ><\/i><\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-514373301 {\n  width: 60%;\n}\n#text-box-514373301 .text {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-514373301 {\n    width: 100%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1810079734 {\n  padding-top: 450px;\n}\n#banner-1810079734 .bg.bg-loaded {\n  background-image: url(https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/03\/Plano-de-Sa\u00fade-Bradesco-SPG-1024x320.jpg);\n}\n#banner-1810079734 .overlay {\n  background-color: rgba(1, 1, 1, 0.55);\n}\n<\/style>\n  <\/div>\n\n\n\t<div id=\"gap-877968572\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-877968572 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-828397981\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-828397981 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-109074986\">\n\n\t<div id=\"col-1449642972\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-837105588\">\n\n\t<div id=\"col-207663743\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h1><span style=\"color: #990909; font-size: 120%;\"><strong>Plano de Sa\u00fade Bradesco<\/strong><\/span><\/h1>\n<p>Sin\u00f4nimo de qualidade, credibilidade, solidez e seguran\u00e7a, a Bradesco Sa\u00fade est\u00e1 presente em todo o territ\u00f3rio nacional, com produtos criados para atender ao segmento empresarial da melhor forma poss\u00edvel:<br \/><span style=\"color: #ed1c24;\"><strong><span style=\"color: #3366ff;\"><i class=\"fa fa-check-square-o \" ><\/i><\/span> <\/strong><\/span>Na diversidade dos produtos e nas op\u00e7\u00f5es de contrata\u00e7\u00e3o;<br \/><span style=\"color: #3366ff;\"><strong><i class=\"fa fa-check-square-o \" ><\/i> <\/strong><\/span>Na abrang\u00eancia da Rede Referenciada, composta por profissionais reconhecidos e centros de refer\u00eancia em todos os campos da medicina;<br \/><span style=\"color: #3366ff;\"><strong><i class=\"fa fa-check-square-o \" ><\/i> <\/strong><\/span>Na valoriza\u00e7\u00e3o do sistema de atendimento, por meio de constantes investimentos em informatiza\u00e7\u00e3o e treinamento de pessoal especializado;<br \/><span style=\"color: #3366ff;\"><strong><i class=\"fa fa-check-square-o \" ><\/i> <\/strong><\/span>Na tecnologia empregada em suas opera\u00e7\u00f5es.<\/p>\n<div class=\"row\"  id=\"row-227840539\">\n\n\t<div id=\"col-1796673777\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li>Plano Empresarial Bradesco MEI<\/li>\n<li>Plano de Sa\u00fade Bradesco CNPJ<\/li>\n<li>Plano Fam\u00edlia Bradesco Sa\u00fade<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\n<style>\n#col-1796673777 > .col-inner {\n  padding: 10px 10px 10px 20px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-663996290\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li>Plano Individual Bradesco Sa\u00fade<\/li>\n<li>Plano de Sa\u00fade Bradesco Pessoa F\u00edsica<\/li>\n<li>Plano Bradesco Sa\u00fade Ades\u00e3o<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\n<style>\n#col-663996290 > .col-inner {\n  padding: 10px 10px 10px 20px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1719581381\">\n\n\t<div id=\"col-899749582\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2><span style=\"color: #8c0606;\">Plano de Sa\u00fade Bradesco?<\/span><\/h2>\n<p>Conhecido como\u00a0<strong>Plano de Sa\u00fade por Ades\u00e3o<\/strong>, o\u00a0<strong>Plano de Sa\u00fade Bradesco Individual<\/strong>\u00a0para Pessoa F\u00edsica \u00e9 um produto coletivo por ades\u00e3o e oferece valores diferenciados no contrato.<\/p>\n<p>J\u00e1 o Plano de Sa\u00fade Bradesco Empresarial \u00e9 um produto oferecido para pessoa que tenha CNPJ ou Mei.<\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\n<style>\n#col-207663743 > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-335630998\">\n\n\t<div id=\"col-569402260\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2><span style=\"color: #a60707;\">Plano de Sa\u00fade Bradesco Empresarial<\/span><\/h2>\n<p>A maioria dos empres\u00e1rios j\u00e1 se conscientizou sobre a import\u00e2ncia de cuidar da sa\u00fade dos seus colaboradores. E escolher um bom plano de sa\u00fade empresarial \u00e9 um investimento imprescind\u00edvel. A Bradesco Sa\u00fade oferece o melhor custo ben\u00e9fico para todos as empresas que queiram contratar o plano de sa\u00fade para seus funcion\u00e1rios.<\/p>\n<p>Atuando na \u00e1rea de seguro-sa\u00fade desde 1984, a <a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/\" target=\"_blank\" rel=\"noopener noreferrer\">Bradesco Sa\u00fade<\/a> tornou-se l\u00edder no mercado\u00a0 \u00a0suplementar brasileiro devido \u00e0 aten\u00e7\u00e3o dada \u00e0s necessidades dos Benefici\u00e1rios e parceria com a Rede Referenciada.<\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-569402260 > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-235825768\">\n\n\t<div id=\"col-1972151613\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2><span style=\"color: #a60707;\">Modalidade de Contrata\u00e7\u00e3o Plano de Sa\u00fade Bradesco<\/span><\/h2>\n<p><strong><span style=\"color: #3366ff;\"><i class=\"fa fa-check-square-o \" ><\/i> <\/span>Compuls\u00f3ria: <\/strong>Inclus\u00e3o de todo o grupo segur\u00e1vel, desde que na totalidade do grupo ou subgrupo definido, e independente do tamanho do quadro funcional do Contratante. V\u00e1lida para os titulares e todos os seus dependentes.<\/p>\n<p><strong><span style=\"color: #3366ff;\"><i class=\"fa fa-check-square-o \" ><\/i> <\/span>Opcional: <\/strong>N\u00e3o h\u00e1 obrigatoriedade de inclus\u00e3o de todo o grupo segur\u00e1vel vinculado ao Contratante.<\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-1972151613 > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1346779019\">\n\n\t<div id=\"col-1915236241\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-484581335\">\n\n\t<div id=\"col-2107344947\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2><span style=\"color: #a60707;\">Quem Pode Contratar o Plano de Sa\u00fade Bradesco?<\/span><\/h2>\n<p>O plano empresarial pode ser contratado por todos que possui uma empresa CNPJ a partir de 3 pessoas sendo 1 titular e 2 dependentes. A Bradesco Sa\u00fade Disponibiliza uma ampla rede de consult\u00f3rios, cl\u00ednicas, laborat\u00f3rios e hospitais, al\u00e9m de possibilitar o reembolso das despesas m\u00e9dicas e hospitalares realizadas por prestadores de sua livre escolha.<\/p>\n<p>Com o melhor atendimento e os mais completos servi\u00e7os, o plano da Bradesco Sa\u00fade com CNPJ proporcionam a prote\u00e7\u00e3o e a tranquilidade que voc\u00ea deseja para a sua Fam\u00edlia ou funcion\u00e1rios da sua empresa.<\/p>\n<div class=\"row\"  id=\"row-609142519\">\n\n\n\t<div id=\"col-2058607519\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-406184053\">\n\n\n\t<div id=\"col-2038704975\" class=\"col medium-3 small-6 large-3\"  >\n\t\t<div class=\"col-inner text-center box-shadow-3 box-shadow-4-hover\"  >\n\t\t\t\n\t\t\t\n\n<p><span style=\"font-size: 120%;\"><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano\/individual\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #ed1c24;\"><i class=\"fa fa-user \" ><\/i><\/span><\/a><\/span><\/p>\n<p><span style=\"font-size: 120%;\"><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano\/individual\/\" target=\"_blank\" rel=\"noopener noreferrer\">Para Voc\u00ea<\/a><\/span><\/p>\n\n\t\t<\/div>\n\t\t\n<style>\n#col-2038704975 > .col-inner {\n  padding: 7px 7px 7px 7px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2021422722\" class=\"col medium-3 small-6 large-3\"  >\n\t\t<div class=\"col-inner text-center box-shadow-3 box-shadow-4-hover\"  >\n\t\t\t\n\t\t\t\n\n<p><span style=\"font-size: 115%;\"><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/bradesco-saude-familiar\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #ed1c24;\"><i class=\"fa fa-users \" ><\/i><\/span><\/a><\/span><\/p>\n<p><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/bradesco-saude-familiar\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-size: 115%;\">Para Fam\u00edlia<\/span><\/a><\/p>\n\n\t\t<\/div>\n\t\t\n<style>\n#col-2021422722 > .col-inner {\n  padding: 7px 7px 7px 7px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-52609917\" class=\"col medium-3 small-6 large-3\"  >\n\t\t<div class=\"col-inner text-center box-shadow-3 box-shadow-4-hover\"  >\n\t\t\t\n\t\t\t\n\n<p><span style=\"font-size: 120%;\"><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/bradesco-saude-mei\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #ed1c24;\"><i class=\"fa fa-university \" ><\/i><\/span><\/a><\/span><\/p>\n<p><span style=\"font-size: 120%;\"><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/bradesco-saude-mei\/\" target=\"_blank\" rel=\"noopener noreferrer\">Para MEI<\/a><\/span><\/p>\n\n\t\t<\/div>\n\t\t\n<style>\n#col-52609917 > .col-inner {\n  padding: 7px 7px 7px 7px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-728184070\" class=\"col medium-3 small-6 large-3\"  >\n\t\t<div class=\"col-inner text-center box-shadow-3 box-shadow-4-hover\"  >\n\t\t\t\n\t\t\t\n\n<p><span style=\"font-size: 120%;\"><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-empresarial\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #ed1c24;\"><i class=\"fa fa-university \" ><\/i><\/span><\/a><\/span><\/p>\n<p><span style=\"font-size: 120%;\"><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-empresarial\/\" target=\"_blank\" rel=\"noopener noreferrer\">Para Empresa<\/a><\/span><\/p>\n\n\t\t<\/div>\n\t\t\n<style>\n#col-728184070 > .col-inner {\n  padding: 7px 7px 7px 7px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\n<style>\n#col-2058607519 > .col-inner {\n  padding: 20px 20px 20px 20px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\t\t<\/div>\n\t\t\n<style>\n#col-2107344947 > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-2094674631\">\n\n\t<div id=\"col-2095471072\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner box-shadow-3\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_541400130\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-zoom-long dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"306\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-individual-Ades\u00e3o.png\" class=\"attachment-large size-large\" alt=\"Bradesco Sa\u00fade individual Ades\u00e3o\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-individual-Ades\u00e3o.png 500w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-individual-Ades\u00e3o-300x184.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_541400130 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-977253833\" class=\"col medium-8 small-12 large-8\"  >\n\t\t<div class=\"col-inner box-shadow-3\"  >\n\t\t\t\n\t\t\t\n<h3>Plano de Sa\u00fade Bradesco Individual<\/h3>\n<p><span style=\"font-size: 105%;\">Plano Bradesco Sa\u00fade Individual Possui um atendimento diferenciado, conforto e qualidade. Esse plano foi pensado para atender a quem procura por uma Rede Referenciada exclusiva, dispon\u00edvel em todas as regi\u00f5es do Brasil, pois conta com hospitais que s\u00e3o refer\u00eancia em servi\u00e7os de sa\u00fade no Pa\u00eds. Possui flexibilidade na escolha de padr\u00e3o de reembolso, que \u00e9 v\u00e1lido para atendimento no Brasil e no Exterior.<\/span><\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-977253833 > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-418384974\">\n\n\t<div id=\"col-2130426396\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner box-shadow-3\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1236290441\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-zoom-long dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"306\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-familiar-ades\u00e3o.png\" class=\"attachment-large size-large\" alt=\"Bradesco Sa\u00fade familiar ades\u00e3o\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-familiar-ades\u00e3o.png 500w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-familiar-ades\u00e3o-300x184.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1236290441 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-933413589\" class=\"col medium-8 small-12 large-8\"  >\n\t\t<div class=\"col-inner box-shadow-3\"  >\n\t\t\t\n\t\t\t\n<h3>Plano de Sa\u00fade Bradesco Familiar<\/h3>\n<p><span style=\"font-size: 105%;\">Plano de Sa\u00fade Bradesco Familiar significado de Comodidade de atendimento em todas as regi\u00f5es do Brasil e as vantagens de uma ampla Rede de Referenciados. Um de seus principais benef\u00edcios \u00e9 o acesso \u00e0s diversas op\u00e7\u00f5es de padr\u00f5es de plano, que preveem diferentes m\u00faltiplos de reembolso para atendimentos realizados no Brasil e no Exterior.<\/span><\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-933413589 > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-594892551\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_426332446\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-zoom-long dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_426332446 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1077365511\">\n\n\t<div id=\"col-1067881383\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1560809701\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-zoom-long dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"306\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-empresarial-2.png\" class=\"attachment-large size-large\" alt=\"Bradesco Sa\u00fade empresarial\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-empresarial-2.png 500w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Bradesco-Sa\u00fade-empresarial-2-300x184.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1560809701 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1464281106\" class=\"col medium-8 small-12 large-8\"  >\n\t\t<div class=\"col-inner box-shadow-3\"  >\n\t\t\t\n\t\t\t\n<h3>Plano de Sa\u00fade Bradesco Empresarial<\/h3>\n<p><span style=\"font-size: 105%;\">Atendimento diferenciado, conforto e qualidade. O plano Bradesco Sa\u00fade Empresarial foi pensado para atender a quem procura por uma Rede Referenciada exclusiva, dispon\u00edvel em todas as regi\u00f5es do Brasil, pois conta com hospitais que s\u00e3o refer\u00eancia em servi\u00e7os de sa\u00fade no Pa\u00eds. Possui flexibilidade na <\/span><span style=\"font-size: 105%;\">escolha de padr\u00e3o de reembolso, que \u00e9 v\u00e1lido para atendimento no Brasil e no Exterior.<\/span><\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-1464281106 > .col-inner {\n  padding: 10px 10px 10px 11px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-67720668\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-67720668 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<h2><span style=\"color: #a60707;\">Op\u00e7\u00f5es do Plano de Sa\u00fade Bradesco<\/span><\/h2>\n<p>O valor da mensalidade do plano Bradesco Sa\u00fade inicial do seguro ser\u00e1 diretamente proporcional \u00e0 idade dos Benefici\u00e1rios inclu\u00eddos na ap\u00f3lice e categoria de plano escolhida. Durante a vig\u00eancia do seguro, esse valor estar\u00e1 sujeito a reajuste por mudan\u00e7a de faixa et\u00e1ria de cada Benefici\u00e1rio inclu\u00eddo na ap\u00f3lice, que incidir\u00e1 sobre o valor do pr\u00eamio imediatamente anterior.<\/p>\n<div class=\"row\"  id=\"row-1066803877\">\n\n\t<div id=\"col-1675798939\" class=\"col medium-3 small-6 large-3\"  >\n\t\t<div class=\"col-inner text-center box-shadow-2\"  >\n\t\t\t\n\t\t\t\n<p><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/preferencial-plus\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-size: 120%;\"><strong>Plano Preferencial Plus<\/strong><\/span><\/a><\/p>\n<p><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/preferencial-plus\/\" target=\"_blank\" rel=\"noopener noreferrer\">Saiba Mais<\/a><\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-1675798939 > .col-inner {\n  padding: 7px 7px 7px 7px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-667883923\" class=\"col medium-9 small-12 large-9\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Esse plano \u00e9 ideal para quem deseja a tranquilidade de ser bem cuidado com a vantagem de ser exclusivo, plano diferenciado em todas as regi\u00f5es do Brasil. Com cuidados especiais que v\u00e3o al\u00e9m da sa\u00fade do Bene\ufb01ci\u00e1rio. Com uma exclusiva Rede que contempla hospitais que s\u00e3o refer\u00eancia em servi\u00e7os de sa\u00fade no Pa\u00eds. Com diversas op\u00e7\u00f5es de reembolso, para atendimentos no Brasil e no exterior, sendo respeitados os limites contratuais.<\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1525764819\">\n\n\t<div id=\"col-1816543518\" class=\"col medium-3 small-6 large-3\"  >\n\t\t<div class=\"col-inner text-center box-shadow-2\"  >\n\t\t\t\n\t\t\t\n<p><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/nacional-flex\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-size: 120%;\"><strong>Plano Nacional Flex<\/strong><\/span><\/a><\/p>\n<p>Saiba Mais<\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-1816543518 > .col-inner {\n  padding: 7px 7px 7px 7px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-572470748\" class=\"col medium-9 small-12 large-9\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Oferece atendimento em todas as regi\u00f5es do Brasil, por meio de uma Rede Referenciada bem dimensionada e de custos mais competitivos em rela\u00e7\u00e3o \u00e0s demais redes de abrang\u00eancia nacional. Prev\u00ea reembolso em caso de atendimento no Brasil, sendo respeitados os limites contratuais. Pode ser conjugado com o Plano Dental Padr\u00e3o ou Dental Premium Top.<\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-533066668\">\n\n\t<div id=\"col-22202605\" class=\"col medium-3 small-6 large-3\"  >\n\t\t<div class=\"col-inner text-center box-shadow-2\"  >\n\t\t\t\n\t\t\t\n<p><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-top-nacional\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-size: 120%;\"><strong>Plano Nacional<\/strong><\/span><\/a><\/p>\n<p><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-top-nacional\/\" target=\"_blank\" rel=\"noopener noreferrer\">Saiba Mais<\/a><\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-22202605 > .col-inner {\n  padding: 7px 7px 7px 7px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-784583095\" class=\"col medium-9 small-12 large-9\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Oferece toda a comodidade de atendimento em todas as regi\u00f5es do Brasil e as vantagens de uma ampla Rede de Referenciados. Um dos principais benef\u00edcios desse plano \u00e9 a op\u00e7\u00e3o de escolha do padr\u00e3o de reembolso, que est\u00e1 dispon\u00edvel para atendimentos no Brasil e no exterior, sendo respeitados os limites contratuais. Pode ser conjugado com o Plano Dental Padr\u00e3o ou Dental Premium Top.<\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-214370422\">\n\n\t<div id=\"col-237868968\" class=\"col medium-3 small-6 large-3\"  >\n\t\t<div class=\"col-inner text-center box-shadow-2\"  >\n\t\t\t\n\t\t\t\n<p><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/nacional-plus\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-size: 120%;\"><strong>Plano Nacional Plus<\/strong><\/span><\/a><\/p>\n<p><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/nacional-plus\/\" target=\"_blank\" rel=\"noopener noreferrer\">Saiba Mais<\/a><\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-237868968 > .col-inner {\n  padding: 7px 7px 7px 7px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1997248360\" class=\"col medium-9 small-12 large-9\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Com atendimento em todas as regi\u00f5es do Brasil, conta com uma ampla Rede Referenciada, que contempla hospitais que s\u00e3o refer\u00eancia em servi\u00e7os de sa\u00fade no Pa\u00eds. Possui \ufb02exibilidade na escolha do padr\u00e3o de reembolso, que \u00e9 v\u00e1lido para atendimento no Brasil e no exterior, sendo respeitados os limites contratuais. Pode ser conjugado com o Plano Dental Padr\u00e3o ou Dental Premium Top.<\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-432187659\">\n\n\t<div id=\"col-1835378304\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2><span style=\"color: #a60707;\">Valor Bradesco Sa\u00fade Empresarial<\/span><\/h2>\n<h3><b>Tabela de Valor Bradesco Sa\u00fade Empresarial <\/b><span style=\"font-size: 20.16px;\"><b>Compuls\u00f3rio Sem Coparticipa\u00e7\u00e3o<\/b><\/span><\/h3>\n<p>Inclus\u00e3o de todo o grupo segur\u00e1vel, desde que na totalidade do grupo ou subgrupo definido, e independente do tamanho do quadro funcional da Empresa Contratante. V\u00e1lida para os Titulares e todos os seus dependentes.<\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-1835378304 > .col-inner {\n  padding: 10px 10px 10px 10px;\n  margin: 0px 0px -21px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-539650419\">\n\n\t<div id=\"col-329286502\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"tabbed-content\">\n\t\t\t\n\t\t\t<ul class=\"nav nav-tabs nav-uppercase nav-size-normal nav-left\"><li class=\"tab active has-icon\"><a href=\"#tab_estado-sp\"><span>ESTADO SP<\/span><\/a><\/li>\n<li class=\"tab has-icon\"><a href=\"#tab_estado-ba\"><span>ESTADO BA<\/span><\/a><\/li>\n<li class=\"tab has-icon\"><a href=\"#tab_estado-df\"><span>ESTADO DF<\/span><\/a><\/li>\n<li class=\"tab has-icon\"><a href=\"#tab_estado-go\"><span>ESTADO GO<\/span><\/a><\/li>\n<li class=\"tab has-icon\"><a href=\"#tab_estado-ma\"><span>ESTADO MA<\/span><\/a><\/li>\n<li class=\"tab has-icon\"><a href=\"#tab_estado-mt\"><span>ESTADO MT<\/span><\/a><\/li>\n<li class=\"tab has-icon\"><a href=\"#tab_estado-mg\"><span>ESTADO MG<\/span><\/a><\/li>\n<li class=\"tab has-icon\"><a href=\"#tab_estado-pr\"><span>ESTADO PR<\/span><\/a><\/li>\n<li class=\"tab has-icon\"><a href=\"#tab_estado-rj\"><span>ESTADO RJ<\/span><\/a><\/li><\/ul><div class=\"tab-panels\"><div class=\"panel active entry-content\" id=\"tab_estado-sp\">\r\n<div class=\"ta-c\"><b>TABELA BRADESCO SA\u00daDE EMPRESARIAL S\u00c3O PAULO COMPULS\u00d3RIO<\/b><\/div>\r\n<div><\/div>\r\n<div class=\"ta-c\">Taxa de Inscri\u00e7\u00e3o: (Por Contrato) - R$ 7,50 por vida, acrescentar IOF de 2,38% sobre o valor total final<\/div>\r\n<table class=\"static small ta-c\">\r\n<tbody>\r\n<tr class=\"bgGray\">\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">Faixa Et\u00e1ria<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">FLEX (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">FLEX (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TPE (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TPQ (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNE (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNQ (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TQN2 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TQN3 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNP4 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNP6 (A)<\/span><\/strong><\/td>\r\n<\/tr>\r\n<tr>\r\n<td>0 a 18 anos<\/td>\r\n<td>R$ 304,66<\/td>\r\n<td>R$ 338,51<\/td>\r\n<td>R$ 329,75<\/td>\r\n<td>R$ 387,95<\/td>\r\n<td>R$ 358,42<\/td>\r\n<td>R$ 421,68<\/td>\r\n<td>R$ 434,33<\/td>\r\n<td>R$ 468,07<\/td>\r\n<td>R$ 927,69<\/td>\r\n<td>R$ 1.079,51<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>19 a 23 anos<\/td>\r\n<td>R$ 359,50<\/td>\r\n<td>R$ 399,44<\/td>\r\n<td>R$ 389,11<\/td>\r\n<td>R$ 457,78<\/td>\r\n<td>R$ 422,95<\/td>\r\n<td>R$ 497,58<\/td>\r\n<td>R$ 512,51<\/td>\r\n<td>R$ 552,31<\/td>\r\n<td>R$ 1.094,68<\/td>\r\n<td>R$ 1.273,82<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>24 a 28 anos<\/td>\r\n<td>R$ 435,00<\/td>\r\n<td>R$ 483,33<\/td>\r\n<td>R$ 470,82<\/td>\r\n<td>R$ 553,91<\/td>\r\n<td>R$ 511,77<\/td>\r\n<td>R$ 602,07<\/td>\r\n<td>R$ 620,13<\/td>\r\n<td>R$ 668,30<\/td>\r\n<td>R$ 1.324,57<\/td>\r\n<td>R$ 1.541,32<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>29 a 33 anos<\/td>\r\n<td>R$ 522,00<\/td>\r\n<td>R$ 579,99<\/td>\r\n<td>R$ 564,98<\/td>\r\n<td>R$ 664,69<\/td>\r\n<td>R$ 614,11<\/td>\r\n<td>R$ 722,49<\/td>\r\n<td>R$ 744,16<\/td>\r\n<td>R$ 801,96<\/td>\r\n<td>R$ 1.589,48<\/td>\r\n<td>R$ 1.849,59<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>34 a 38 anos<\/td>\r\n<td>R$ 595,07<\/td>\r\n<td>R$ 661,20<\/td>\r\n<td>R$ 644,08<\/td>\r\n<td>R$ 757,75<\/td>\r\n<td>R$ 700,09<\/td>\r\n<td>R$ 823,64<\/td>\r\n<td>R$ 848,35<\/td>\r\n<td>R$ 914,24<\/td>\r\n<td>R$ 1.812,01<\/td>\r\n<td>R$ 2.108,53<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>39 a 43 anos<\/td>\r\n<td>R$ 612,94<\/td>\r\n<td>R$ 681,03<\/td>\r\n<td>R$ 663,41<\/td>\r\n<td>R$ 780,48<\/td>\r\n<td>R$ 721,09<\/td>\r\n<td>R$ 848,35<\/td>\r\n<td>R$ 873,80<\/td>\r\n<td>R$ 941,66<\/td>\r\n<td>R$ 1.866,38<\/td>\r\n<td>R$ 2.171,78<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>44 a 48 anos<\/td>\r\n<td>R$ 746,27<\/td>\r\n<td>R$ 829,19<\/td>\r\n<td>R$ 807,74<\/td>\r\n<td>R$ 950,28<\/td>\r\n<td>R$ 877,97<\/td>\r\n<td>R$ 1.032,91<\/td>\r\n<td>R$ 1.063,89<\/td>\r\n<td>R$ 1.146,53<\/td>\r\n<td>R$ 2.272,41<\/td>\r\n<td>R$ 2.644,25<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>49 a 53 anos<\/td>\r\n<td>R$ 877,77<\/td>\r\n<td>R$ 975,30<\/td>\r\n<td>R$ 950,06<\/td>\r\n<td>R$ 1.117,71<\/td>\r\n<td>R$ 1.032,67<\/td>\r\n<td>R$ 1.214,91<\/td>\r\n<td>R$ 1.251,35<\/td>\r\n<td>R$ 1.348,55<\/td>\r\n<td>R$ 2.672,81<\/td>\r\n<td>R$ 3.110,18<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>54 a 58 anos<\/td>\r\n<td>R$ 1.044,54<\/td>\r\n<td>R$ 1.160,61<\/td>\r\n<td>R$ 1.130,57<\/td>\r\n<td>R$ 1.330,09<\/td>\r\n<td>R$ 1.228,88<\/td>\r\n<td>R$ 1.445,74<\/td>\r\n<td>R$ 1.489,12<\/td>\r\n<td>R$ 1.604,78<\/td>\r\n<td>R$ 3.180,64<\/td>\r\n<td>R$ 3.701,10<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>+ de 59 anos<\/td>\r\n<td>R$ 1.827,96<\/td>\r\n<td>R$ 2.031,07<\/td>\r\n<td>R$ 1.978,50<\/td>\r\n<td>R$ 2.327,65<\/td>\r\n<td>R$ 2.150,54<\/td>\r\n<td>R$ 2.530,06<\/td>\r\n<td>R$ 2.605,96<\/td>\r\n<td>R$ 2.808,36<\/td>\r\n<td>R$ 5.566,13<\/td>\r\n<td>R$ 6.476,94<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<\/div>\n<div class=\"panel entry-content\" id=\"tab_estado-ba\">\r\n<div class=\"ta-c\"><b>TABELA BRADESCO SA\u00daDE EMPRESARIAL BAHIA COMPULS\u00d3RIO<\/b><\/div>\r\n<div><\/div>\r\n<div class=\"ta-c\">Taxa de Inscri\u00e7\u00e3o: (Por Contrato) - R$ 7,50 por vida, acrescentar IOF de 2,38% sobre o valor total final<\/div>\r\n<table class=\"static small ta-c\">\r\n<tbody>\r\n<tr class=\"bgGray\">\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">Faixa Et\u00e1ria<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">FLEX (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">FLEX (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNE (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNQ (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TQN2 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TQN3 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNP4 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNP6 (A)<\/span><\/strong><\/td>\r\n<\/tr>\r\n<tr>\r\n<td>0 a 18 anos<\/td>\r\n<td>R$ 324,98<\/td>\r\n<td>R$ 361,09<\/td>\r\n<td>R$ 361,09<\/td>\r\n<td>R$ 401,20<\/td>\r\n<td>R$ 413,24<\/td>\r\n<td>R$ 445,33<\/td>\r\n<td>R$ 882,66<\/td>\r\n<td>R$ 1.027,09<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>19 a 23 anos<\/td>\r\n<td>R$ 383,47<\/td>\r\n<td>R$ 426,08<\/td>\r\n<td>R$ 426,08<\/td>\r\n<td>R$ 473,42<\/td>\r\n<td>R$ 487,62<\/td>\r\n<td>R$ 525,50<\/td>\r\n<td>R$ 1.041,54<\/td>\r\n<td>R$ 1.211,97<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>24 a 28 anos<\/td>\r\n<td>R$ 464,00<\/td>\r\n<td>R$ 515,56<\/td>\r\n<td>R$ 515,56<\/td>\r\n<td>R$ 572,84<\/td>\r\n<td>R$ 590,02<\/td>\r\n<td>R$ 635,86<\/td>\r\n<td>R$ 1.260,26<\/td>\r\n<td>R$ 1.466,48<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>29 a 33 anos<\/td>\r\n<td>R$ 556,80<\/td>\r\n<td>R$ 618,67<\/td>\r\n<td>R$ 618,67<\/td>\r\n<td>R$ 687,41<\/td>\r\n<td>R$ 708,03<\/td>\r\n<td>R$ 763,02<\/td>\r\n<td>R$ 1.512,30<\/td>\r\n<td>R$ 1.759,78<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>34 a 38 anos<\/td>\r\n<td>R$ 634,76<\/td>\r\n<td>R$ 705,28<\/td>\r\n<td>R$ 705,28<\/td>\r\n<td>R$ 783,65<\/td>\r\n<td>R$ 807,16<\/td>\r\n<td>R$ 869,85<\/td>\r\n<td>R$ 1.724,03<\/td>\r\n<td>R$ 2.006,15<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>39 a 43 anos<\/td>\r\n<td>R$ 653,80<\/td>\r\n<td>R$ 726,44<\/td>\r\n<td>R$ 726,44<\/td>\r\n<td>R$ 807,16<\/td>\r\n<td>R$ 831,37<\/td>\r\n<td>R$ 895,94<\/td>\r\n<td>R$ 1.775,76<\/td>\r\n<td>R$ 2.066,33<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>44 a 48 anos<\/td>\r\n<td>R$ 796,03<\/td>\r\n<td>R$ 884,48<\/td>\r\n<td>R$ 884,48<\/td>\r\n<td>R$ 982,75<\/td>\r\n<td>R$ 1.012,24<\/td>\r\n<td>R$ 1.090,86<\/td>\r\n<td>R$ 2.162,07<\/td>\r\n<td>R$ 2.515,86<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>49 a 53 anos<\/td>\r\n<td>R$ 936,29<\/td>\r\n<td>R$ 1.040,33<\/td>\r\n<td>R$ 1.040,33<\/td>\r\n<td>R$ 1.155,92<\/td>\r\n<td>R$ 1.190,59<\/td>\r\n<td>R$ 1.283,07<\/td>\r\n<td>R$ 2.543,03<\/td>\r\n<td>R$ 2.959,16<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>54 a 58 anos<\/td>\r\n<td>R$ 1.114,19<\/td>\r\n<td>R$ 1.237,99<\/td>\r\n<td>R$ 1.237,99<\/td>\r\n<td>R$ 1.375,54<\/td>\r\n<td>R$ 1.416,81<\/td>\r\n<td>R$ 1.526,86<\/td>\r\n<td>R$ 3.026,20<\/td>\r\n<td>R$ 3.521,40<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>+ de 59 anos<\/td>\r\n<td>R$ 1.949,83<\/td>\r\n<td>R$ 2.166,49<\/td>\r\n<td>R$ 2.166,49<\/td>\r\n<td>R$ 2.407,21<\/td>\r\n<td>R$ 2.479,42<\/td>\r\n<td>R$ 2.672,00<\/td>\r\n<td>R$ 5.295,85<\/td>\r\n<td>R$ 6.162,45<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<\/div>\n<div class=\"panel entry-content\" id=\"tab_estado-df\">\r\n<div class=\"ta-c\"><b>TABELA BRADESCO SA\u00daDE EMPRESARIAL BRAS\u00cdLIA COMPULS\u00d3RIO<\/b><\/div>\r\n<div><\/div>\r\n<div class=\"ta-c\">Taxa de Inscri\u00e7\u00e3o: (Por Contrato) - R$ 7,50 por vida, acrescentar IOF de 2,38% sobre o valor total final<\/div>\r\n<table class=\"static small ta-c\">\r\n<tbody>\r\n<tr class=\"bgGray\">\r\n<td style=\"background-color: #a31010;\"><span style=\"color: #fafafa;\"><strong>Faixa Et\u00e1ria<\/strong><\/span><\/td>\r\n<td style=\"background-color: #a31010;\"><span style=\"color: #fafafa;\"><strong>FLEX (E)<\/strong><\/span><\/td>\r\n<td style=\"background-color: #a31010;\"><span style=\"color: #fafafa;\"><strong>FLEX (A)<\/strong><\/span><\/td>\r\n<td style=\"background-color: #a31010;\"><span style=\"color: #fafafa;\"><strong>TNE (E)<\/strong><\/span><\/td>\r\n<td style=\"background-color: #a31010;\"><span style=\"color: #fafafa;\"><strong>TNQ (A)<\/strong><\/span><\/td>\r\n<td style=\"background-color: #a31010;\"><span style=\"color: #fafafa;\"><strong>TQN2 (A)<\/strong><\/span><\/td>\r\n<td style=\"background-color: #a31010;\"><span style=\"color: #fafafa;\"><strong>TQN3 (A)<\/strong><\/span><\/td>\r\n<td style=\"background-color: #a31010;\"><span style=\"color: #fafafa;\"><strong>TNP4 (A)<\/strong><\/span><\/td>\r\n<td style=\"background-color: #a31010;\"><span style=\"color: #fafafa;\"><strong>TNP6 (A)<\/strong><\/span><\/td>\r\n<\/tr>\r\n<tr>\r\n<td>0 a 18 anos<\/td>\r\n<td>R$ 361,31<\/td>\r\n<td>R$ 401,45<\/td>\r\n<td>R$ 384,37<\/td>\r\n<td>R$ 427,08<\/td>\r\n<td>R$ 439,90<\/td>\r\n<td>R$ 474,06<\/td>\r\n<td>R$ 939,59<\/td>\r\n<td>R$ 1.093,34<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>19 a 23 anos<\/td>\r\n<td>R$ 426,34<\/td>\r\n<td>R$ 473,72<\/td>\r\n<td>R$ 453,56<\/td>\r\n<td>R$ 503,96<\/td>\r\n<td>R$ 519,07<\/td>\r\n<td>R$ 559,39<\/td>\r\n<td>R$ 1.108,70<\/td>\r\n<td>R$ 1.290,14<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>24 a 28 anos<\/td>\r\n<td>R$ 515,88<\/td>\r\n<td>R$ 573,20<\/td>\r\n<td>R$ 548,81<\/td>\r\n<td>R$ 609,79<\/td>\r\n<td>R$ 628,08<\/td>\r\n<td>R$ 676,87<\/td>\r\n<td>R$ 1.341,53<\/td>\r\n<td>R$ 1.561,07<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>29 a 33 anos<\/td>\r\n<td>R$ 619,05<\/td>\r\n<td>R$ 687,84<\/td>\r\n<td>R$ 658,57<\/td>\r\n<td>R$ 731,75<\/td>\r\n<td>R$ 753,70<\/td>\r\n<td>R$ 812,24<\/td>\r\n<td>R$ 1.609,85<\/td>\r\n<td>R$ 1.873,27<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>34 a 38 anos<\/td>\r\n<td>R$ 705,73<\/td>\r\n<td>R$ 784,14<\/td>\r\n<td>R$ 750,77<\/td>\r\n<td>R$ 834,19<\/td>\r\n<td>R$ 859,22<\/td>\r\n<td>R$ 925,95<\/td>\r\n<td>R$ 1.835,22<\/td>\r\n<td>R$ 2.135,54<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>39 a 43 anos<\/td>\r\n<td>R$ 726,89<\/td>\r\n<td>R$ 807,67<\/td>\r\n<td>R$ 773,29<\/td>\r\n<td>R$ 859,22<\/td>\r\n<td>R$ 884,99<\/td>\r\n<td>R$ 953,73<\/td>\r\n<td>R$ 1.890,28<\/td>\r\n<td>R$ 2.199,60<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>44 a 48 anos<\/td>\r\n<td>R$ 885,03<\/td>\r\n<td>R$ 983,37<\/td>\r\n<td>R$ 941,53<\/td>\r\n<td>R$ 1.046,14<\/td>\r\n<td>R$ 1.077,52<\/td>\r\n<td>R$ 1.161,22<\/td>\r\n<td>R$ 2.301,51<\/td>\r\n<td>R$ 2.678,12<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>49 a 53 anos<\/td>\r\n<td>R$ 1.040,98<\/td>\r\n<td>R$ 1.156,64<\/td>\r\n<td>R$ 1.107,43<\/td>\r\n<td>R$ 1.230,47<\/td>\r\n<td>R$ 1.267,38<\/td>\r\n<td>R$ 1.365,82<\/td>\r\n<td>R$ 2.707,04<\/td>\r\n<td>R$ 3.150,01<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>54 a 58 anos<\/td>\r\n<td>R$ 1.238,76<\/td>\r\n<td>R$ 1.376,40<\/td>\r\n<td>R$ 1.317,83<\/td>\r\n<td>R$ 1.464,26<\/td>\r\n<td>R$ 1.508,18<\/td>\r\n<td>R$ 1.625,33<\/td>\r\n<td>R$ 3.221,38<\/td>\r\n<td>R$ 3.748,52<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>+ de 59 anos<\/td>\r\n<td>R$ 2.167,84<\/td>\r\n<td>R$ 2.408,71<\/td>\r\n<td>R$ 2.306,22<\/td>\r\n<td>R$ 2.562,46<\/td>\r\n<td>R$ 2.639,33<\/td>\r\n<td>R$ 2.844,33<\/td>\r\n<td>R$ 5.637,42<\/td>\r\n<td>R$ 6.559,91<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<\/div>\n<div class=\"panel entry-content\" id=\"tab_estado-go\">\r\n<div class=\"ta-c\"><b>TABELA BRADESCO SA\u00daDE EMPRESARIAL GOIAS COMPULS\u00d3RIO<\/b><\/div>\r\n<div><\/div>\r\n<div class=\"ta-c\">Taxa de Inscri\u00e7\u00e3o: (Por Contrato) - R$ 7,50 por vida, acrescentar IOF de 2,38% sobre o valor total final<\/div>\r\n<table class=\"static small ta-c\">\r\n<tbody>\r\n<tr class=\"bgGray\">\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">Faixa Et\u00e1ria<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">FLEX (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">FLEX (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNE (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNQ (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TQN2 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TQN3 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNP4 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNP6 (A)<\/span><\/strong><\/td>\r\n<\/tr>\r\n<tr>\r\n<td>0 a 18 anos<\/td>\r\n<td>R$ 190,47<\/td>\r\n<td>R$ 211,64<\/td>\r\n<td>R$ 202,63<\/td>\r\n<td>R$ 244,14<\/td>\r\n<td>R$ 251,46<\/td>\r\n<td>R$ 270,99<\/td>\r\n<td>R$ 537,10<\/td>\r\n<td>R$ 624,99<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>19 a 23 anos<\/td>\r\n<td>R$ 224,76<\/td>\r\n<td>R$ 249,73<\/td>\r\n<td>R$ 239,11<\/td>\r\n<td>R$ 288,08<\/td>\r\n<td>R$ 296,72<\/td>\r\n<td>R$ 319,77<\/td>\r\n<td>R$ 633,79<\/td>\r\n<td>R$ 737,50<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>24 a 28 anos<\/td>\r\n<td>R$ 271,96<\/td>\r\n<td>R$ 302,18<\/td>\r\n<td>R$ 289,31<\/td>\r\n<td>R$ 348,58<\/td>\r\n<td>R$ 359,04<\/td>\r\n<td>R$ 386,93<\/td>\r\n<td>R$ 766,87<\/td>\r\n<td>R$ 892,37<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>29 a 33 anos<\/td>\r\n<td>R$ 326,35<\/td>\r\n<td>R$ 362,61<\/td>\r\n<td>R$ 347,18<\/td>\r\n<td>R$ 418,29<\/td>\r\n<td>R$ 430,85<\/td>\r\n<td>R$ 464,31<\/td>\r\n<td>R$ 920,26<\/td>\r\n<td>R$ 1.070,84<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>34 a 38 anos<\/td>\r\n<td>R$ 372,05<\/td>\r\n<td>R$ 413,38<\/td>\r\n<td>R$ 395,79<\/td>\r\n<td>R$ 476,86<\/td>\r\n<td>R$ 491,16<\/td>\r\n<td>R$ 529,31<\/td>\r\n<td>R$ 1.049,09<\/td>\r\n<td>R$ 1.220,76<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>39 a 43 anos<\/td>\r\n<td>R$ 383,20<\/td>\r\n<td>R$ 425,78<\/td>\r\n<td>R$ 407,66<\/td>\r\n<td>R$ 491,16<\/td>\r\n<td>R$ 505,90<\/td>\r\n<td>R$ 545,19<\/td>\r\n<td>R$ 1.080,56<\/td>\r\n<td>R$ 1.257,38<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>44 a 48 anos<\/td>\r\n<td>R$ 466,57<\/td>\r\n<td>R$ 518,41<\/td>\r\n<td>R$ 496,35<\/td>\r\n<td>R$ 598,01<\/td>\r\n<td>R$ 615,95<\/td>\r\n<td>R$ 663,80<\/td>\r\n<td>R$ 1.315,64<\/td>\r\n<td>R$ 1.530,93<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>49 a 53 anos<\/td>\r\n<td>R$ 548,79<\/td>\r\n<td>R$ 609,76<\/td>\r\n<td>R$ 583,81<\/td>\r\n<td>R$ 703,39<\/td>\r\n<td>R$ 724,49<\/td>\r\n<td>R$ 780,77<\/td>\r\n<td>R$ 1.547,46<\/td>\r\n<td>R$ 1.800,68<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>54 a 58 anos<\/td>\r\n<td>R$ 653,05<\/td>\r\n<td>R$ 725,62<\/td>\r\n<td>R$ 694,74<\/td>\r\n<td>R$ 837,03<\/td>\r\n<td>R$ 862,14<\/td>\r\n<td>R$ 929,11<\/td>\r\n<td>R$ 1.841,48<\/td>\r\n<td>R$ 2.142,81<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>+ de 59 anos<\/td>\r\n<td>R$ 1.142,84<\/td>\r\n<td>R$ 1.269,83<\/td>\r\n<td>R$ 1.215,79<\/td>\r\n<td>R$ 1.464,81<\/td>\r\n<td>R$ 1.508,76<\/td>\r\n<td>R$ 1.625,95<\/td>\r\n<td>R$ 3.222,59<\/td>\r\n<td>R$ 3.749,93<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<\/div>\n<div class=\"panel entry-content\" id=\"tab_estado-ma\">\r\n<div class=\"ta-c\"><b>TABELA BRADESCO SA\u00daDE EMPRESARIAL MARANH\u00c3O COMPULS\u00d3RIO<\/b><\/div>\r\n<div><\/div>\r\n<div class=\"ta-c\">Taxa de Inscri\u00e7\u00e3o: (Por Contrato) - R$ 7,50 por vida, acrescentar IOF de 2,38% sobre o valor total final<\/div>\r\n<table class=\"static small ta-c\">\r\n<tbody>\r\n<tr class=\"bgGray\">\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">Faixa Et\u00e1ria<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">FLEX (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">FLEX (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNE (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNQ (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TQN2 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TQN3 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNP4 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNP6 (A)<\/span><\/strong><\/td>\r\n<\/tr>\r\n<tr>\r\n<td>0 a 18 anos<\/td>\r\n<td>R$ 336,92<\/td>\r\n<td>R$ 374,35<\/td>\r\n<td>R$ 358,42<\/td>\r\n<td>R$ 421,68<\/td>\r\n<td>R$ 434,33<\/td>\r\n<td>R$ 468,07<\/td>\r\n<td>R$ 927,69<\/td>\r\n<td>R$ 1.079,51<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>19 a 23 anos<\/td>\r\n<td>R$ 397,57<\/td>\r\n<td>R$ 441,74<\/td>\r\n<td>R$ 422,95<\/td>\r\n<td>R$ 497,58<\/td>\r\n<td>R$ 512,51<\/td>\r\n<td>R$ 552,31<\/td>\r\n<td>R$ 1.094,68<\/td>\r\n<td>R$ 1.273,82<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>24 a 28 anos<\/td>\r\n<td>R$ 481,06<\/td>\r\n<td>R$ 534,51<\/td>\r\n<td>R$ 511,77<\/td>\r\n<td>R$ 602,07<\/td>\r\n<td>R$ 620,13<\/td>\r\n<td>R$ 668,30<\/td>\r\n<td>R$ 1.324,57<\/td>\r\n<td>R$ 1.541,32<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>29 a 33 anos<\/td>\r\n<td>R$ 577,27<\/td>\r\n<td>R$ 641,41<\/td>\r\n<td>R$ 614,11<\/td>\r\n<td>R$ 722,49<\/td>\r\n<td>R$ 744,16<\/td>\r\n<td>R$ 801,96<\/td>\r\n<td>R$ 1.589,48<\/td>\r\n<td>R$ 1.849,59<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>34 a 38 anos<\/td>\r\n<td>R$ 658,08<\/td>\r\n<td>R$ 731,21<\/td>\r\n<td>R$ 700,09<\/td>\r\n<td>R$ 823,64<\/td>\r\n<td>R$ 848,35<\/td>\r\n<td>R$ 914,24<\/td>\r\n<td>R$ 1.812,01<\/td>\r\n<td>R$ 2.108,53<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>39 a 43 anos<\/td>\r\n<td>R$ 677,83<\/td>\r\n<td>R$ 753,14<\/td>\r\n<td>R$ 721,09<\/td>\r\n<td>R$ 848,35<\/td>\r\n<td>R$ 873,80<\/td>\r\n<td>R$ 941,66<\/td>\r\n<td>R$ 1.866,38<\/td>\r\n<td>R$ 2.171,78<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>44 a 48 anos<\/td>\r\n<td>R$ 825,29<\/td>\r\n<td>R$ 916,99<\/td>\r\n<td>R$ 877,97<\/td>\r\n<td>R$ 1.032,91<\/td>\r\n<td>R$ 1.063,89<\/td>\r\n<td>R$ 1.146,53<\/td>\r\n<td>R$ 2.272,41<\/td>\r\n<td>R$ 2.644,25<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>49 a 53 anos<\/td>\r\n<td>R$ 970,71<\/td>\r\n<td>R$ 1.078,56<\/td>\r\n<td>R$ 1.032,67<\/td>\r\n<td>R$ 1.214,91<\/td>\r\n<td>R$ 1.251,35<\/td>\r\n<td>R$ 1.348,55<\/td>\r\n<td>R$ 2.672,81<\/td>\r\n<td>R$ 3.110,18<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>54 a 58 anos<\/td>\r\n<td>R$ 1.155,15<\/td>\r\n<td>R$ 1.283,49<\/td>\r\n<td>R$ 1.228,88<\/td>\r\n<td>R$ 1.445,74<\/td>\r\n<td>R$ 1.489,12<\/td>\r\n<td>R$ 1.604,78<\/td>\r\n<td>R$ 3.180,64<\/td>\r\n<td>R$ 3.701,10<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>+ de 59 anos<\/td>\r\n<td>R$ 2.021,52<\/td>\r\n<td>R$ 2.246,13<\/td>\r\n<td>R$ 2.150,54<\/td>\r\n<td>R$ 2.530,06<\/td>\r\n<td>R$ 2.605,96<\/td>\r\n<td>R$ 2.808,36<\/td>\r\n<td>R$ 5.566,13<\/td>\r\n<td>R$ 6.476,94<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<\/div>\n<div class=\"panel entry-content\" id=\"tab_estado-mt\">\r\n<div class=\"ta-c\"><b>TABELA BRADESCO SA\u00daDE EMPRESARIAL MATO GROSSO COMPULS\u00d3RIO<\/b><\/div>\r\n<div><\/div>\r\n<div class=\"ta-c\">Taxa de Inscri\u00e7\u00e3o: (Por Contrato) - R$ 7,50 por vida, acrescentar IOF de 2,38% sobre o valor total final<\/div>\r\n<table class=\"static small ta-c\">\r\n<tbody>\r\n<tr class=\"bgGray\">\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">Faixa Et\u00e1ria<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">FLEX (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">FLEX (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNE (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNQ (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TQN2 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TQN3 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNP4 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNP6 (A)<\/span><\/strong><\/td>\r\n<\/tr>\r\n<tr>\r\n<td>0 a 18 anos<\/td>\r\n<td>R$ 190,47<\/td>\r\n<td>R$ 211,64<\/td>\r\n<td>R$ 202,63<\/td>\r\n<td>R$ 244,14<\/td>\r\n<td>R$ 251,46<\/td>\r\n<td>R$ 270,99<\/td>\r\n<td>R$ 537,10<\/td>\r\n<td>R$ 624,99<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>19 a 23 anos<\/td>\r\n<td>R$ 224,76<\/td>\r\n<td>R$ 249,73<\/td>\r\n<td>R$ 239,11<\/td>\r\n<td>R$ 288,08<\/td>\r\n<td>R$ 296,72<\/td>\r\n<td>R$ 319,77<\/td>\r\n<td>R$ 633,79<\/td>\r\n<td>R$ 737,50<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>24 a 28 anos<\/td>\r\n<td>R$ 271,96<\/td>\r\n<td>R$ 302,18<\/td>\r\n<td>R$ 289,31<\/td>\r\n<td>R$ 348,58<\/td>\r\n<td>R$ 359,04<\/td>\r\n<td>R$ 386,93<\/td>\r\n<td>R$ 766,87<\/td>\r\n<td>R$ 892,37<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>29 a 33 anos<\/td>\r\n<td>R$ 326,35<\/td>\r\n<td>R$ 362,61<\/td>\r\n<td>R$ 347,18<\/td>\r\n<td>R$ 418,29<\/td>\r\n<td>R$ 430,85<\/td>\r\n<td>R$ 464,31<\/td>\r\n<td>R$ 920,26<\/td>\r\n<td>R$ 1.070,84<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>34 a 38 anos<\/td>\r\n<td>R$ 372,05<\/td>\r\n<td>R$ 413,38<\/td>\r\n<td>R$ 395,79<\/td>\r\n<td>R$ 476,86<\/td>\r\n<td>R$ 491,16<\/td>\r\n<td>R$ 529,31<\/td>\r\n<td>R$ 1.049,09<\/td>\r\n<td>R$ 1.220,76<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>39 a 43 anos<\/td>\r\n<td>R$ 383,20<\/td>\r\n<td>R$ 425,78<\/td>\r\n<td>R$ 407,66<\/td>\r\n<td>R$ 491,16<\/td>\r\n<td>R$ 505,90<\/td>\r\n<td>R$ 545,19<\/td>\r\n<td>R$ 1.080,56<\/td>\r\n<td>R$ 1.257,38<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>44 a 48 anos<\/td>\r\n<td>R$ 466,57<\/td>\r\n<td>R$ 518,41<\/td>\r\n<td>R$ 496,35<\/td>\r\n<td>R$ 598,01<\/td>\r\n<td>R$ 615,95<\/td>\r\n<td>R$ 663,80<\/td>\r\n<td>R$ 1.315,64<\/td>\r\n<td>R$ 1.530,93<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>49 a 53 anos<\/td>\r\n<td>R$ 548,79<\/td>\r\n<td>R$ 609,76<\/td>\r\n<td>R$ 583,81<\/td>\r\n<td>R$ 703,39<\/td>\r\n<td>R$ 724,49<\/td>\r\n<td>R$ 780,77<\/td>\r\n<td>R$ 1.547,46<\/td>\r\n<td>R$ 1.800,68<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>54 a 58 anos<\/td>\r\n<td>R$ 653,05<\/td>\r\n<td>R$ 725,62<\/td>\r\n<td>R$ 694,74<\/td>\r\n<td>R$ 837,03<\/td>\r\n<td>R$ 862,14<\/td>\r\n<td>R$ 929,11<\/td>\r\n<td>R$ 1.841,48<\/td>\r\n<td>R$ 2.142,81<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>+ de 59 anos<\/td>\r\n<td>R$ 1.142,84<\/td>\r\n<td>R$ 1.269,83<\/td>\r\n<td>R$ 1.215,79<\/td>\r\n<td>R$ 1.464,81<\/td>\r\n<td>R$ 1.508,76<\/td>\r\n<td>R$ 1.625,95<\/td>\r\n<td>R$ 3.222,59<\/td>\r\n<td>R$ 3.749,93<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<\/div>\n<div class=\"panel entry-content\" id=\"tab_estado-mg\">\r\n<div class=\"ta-c\"><b>TABELA BRADESCO SA\u00daDE EMPRESARIAL MG COMPULS\u00d3RIO<\/b><\/div>\r\n<div class=\"ta-c\">Taxa de Inscri\u00e7\u00e3o: (Por Contrato) - R$ 7,50 por vida, acrescentar IOF de 2,38% sobre o valor total final<\/div>\r\n<table class=\"static small ta-c\">\r\n<tbody>\r\n<tr class=\"bgGray\">\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">Faixa Et\u00e1ria<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">FLEX (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">FLEX (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNE (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNQ (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TQN2 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TQN3 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNP4 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNP6 (A)<\/span><\/strong><\/td>\r\n<\/tr>\r\n<tr>\r\n<td>0 a 18 anos<\/td>\r\n<td>R$ 212,76<\/td>\r\n<td>R$ 236,40<\/td>\r\n<td>R$ 217,11<\/td>\r\n<td>R$ 256,14<\/td>\r\n<td>R$ 263,82<\/td>\r\n<td>R$ 284,31<\/td>\r\n<td>R$ 563,51<\/td>\r\n<td>R$ 655,72<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>19 a 23 anos<\/td>\r\n<td>R$ 251,06<\/td>\r\n<td>R$ 278,96<\/td>\r\n<td>R$ 256,19<\/td>\r\n<td>R$ 302,24<\/td>\r\n<td>R$ 311,30<\/td>\r\n<td>R$ 335,49<\/td>\r\n<td>R$ 664,93<\/td>\r\n<td>R$ 773,75<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>24 a 28 anos<\/td>\r\n<td>R$ 303,79<\/td>\r\n<td>R$ 337,54<\/td>\r\n<td>R$ 309,99<\/td>\r\n<td>R$ 365,71<\/td>\r\n<td>R$ 376,68<\/td>\r\n<td>R$ 405,95<\/td>\r\n<td>R$ 804,58<\/td>\r\n<td>R$ 936,23<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>29 a 33 anos<\/td>\r\n<td>R$ 364,54<\/td>\r\n<td>R$ 405,05<\/td>\r\n<td>R$ 371,99<\/td>\r\n<td>R$ 438,86<\/td>\r\n<td>R$ 452,03<\/td>\r\n<td>R$ 487,13<\/td>\r\n<td>R$ 965,49<\/td>\r\n<td>R$ 1.123,48<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>34 a 38 anos<\/td>\r\n<td>R$ 415,58<\/td>\r\n<td>R$ 461,76<\/td>\r\n<td>R$ 424,07<\/td>\r\n<td>R$ 500,29<\/td>\r\n<td>R$ 515,30<\/td>\r\n<td>R$ 555,33<\/td>\r\n<td>R$ 1.100,66<\/td>\r\n<td>R$ 1.280,77<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>39 a 43 anos<\/td>\r\n<td>R$ 428,05<\/td>\r\n<td>R$ 475,61<\/td>\r\n<td>R$ 436,78<\/td>\r\n<td>R$ 515,30<\/td>\r\n<td>R$ 530,77<\/td>\r\n<td>R$ 571,99<\/td>\r\n<td>R$ 1.133,68<\/td>\r\n<td>R$ 1.319,20<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>44 a 48 anos<\/td>\r\n<td>R$ 521,17<\/td>\r\n<td>R$ 579,07<\/td>\r\n<td>R$ 531,81<\/td>\r\n<td>R$ 627,41<\/td>\r\n<td>R$ 646,23<\/td>\r\n<td>R$ 696,43<\/td>\r\n<td>R$ 1.380,31<\/td>\r\n<td>R$ 1.606,18<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>49 a 53 anos<\/td>\r\n<td>R$ 613,00<\/td>\r\n<td>R$ 681,11<\/td>\r\n<td>R$ 625,51<\/td>\r\n<td>R$ 737,96<\/td>\r\n<td>R$ 760,10<\/td>\r\n<td>R$ 819,14<\/td>\r\n<td>R$ 1.623,53<\/td>\r\n<td>R$ 1.889,19<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>54 a 58 anos<\/td>\r\n<td>R$ 729,47<\/td>\r\n<td>R$ 810,53<\/td>\r\n<td>R$ 744,36<\/td>\r\n<td>R$ 878,18<\/td>\r\n<td>R$ 904,53<\/td>\r\n<td>R$ 974,77<\/td>\r\n<td>R$ 1.931,99<\/td>\r\n<td>R$ 2.248,14<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>+ de 59 anos<\/td>\r\n<td>R$ 1.276,58<\/td>\r\n<td>R$ 1.418,42<\/td>\r\n<td>R$ 1.302,63<\/td>\r\n<td>R$ 1.536,82<\/td>\r\n<td>R$ 1.582,92<\/td>\r\n<td>R$ 1.705,87<\/td>\r\n<td>R$ 3.381,00<\/td>\r\n<td>R$ 3.934,25<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<\/div>\n<div class=\"panel entry-content\" id=\"tab_estado-pr\">\r\n<div class=\"ta-c\"><b>TABELA BRADESCO SA\u00daDE EMPRESARIAL PR COMPULS\u00d3RIO<\/b><\/div>\r\n<div><\/div>\r\n<div class=\"ta-c\">Taxa de Inscri\u00e7\u00e3o: (Por Contrato) - R$ 7,50 por vida, acrescentar IOF de 2,38% sobre o valor total final<\/div>\r\n<table class=\"static small ta-c\">\r\n<tbody>\r\n<tr class=\"bgGray\">\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">Faixa Et\u00e1ria<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">FLEX (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">FLEX (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNE (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNQ (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TQN2 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TQN3 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNP4 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNP6 (A)<\/span><\/strong><\/td>\r\n<\/tr>\r\n<tr>\r\n<td>0 a 18 anos<\/td>\r\n<td>R$ 223,21<\/td>\r\n<td>R$ 248,01<\/td>\r\n<td>R$ 237,45<\/td>\r\n<td>R$ 260,94<\/td>\r\n<td>R$ 268,77<\/td>\r\n<td>R$ 289,64<\/td>\r\n<td>R$ 574,07<\/td>\r\n<td>R$ 668,01<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>19 a 23 anos<\/td>\r\n<td>R$ 263,38<\/td>\r\n<td>R$ 292,65<\/td>\r\n<td>R$ 280,20<\/td>\r\n<td>R$ 307,91<\/td>\r\n<td>R$ 317,15<\/td>\r\n<td>R$ 341,78<\/td>\r\n<td>R$ 677,41<\/td>\r\n<td>R$ 788,25<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>24 a 28 anos<\/td>\r\n<td>R$ 318,70<\/td>\r\n<td>R$ 354,11<\/td>\r\n<td>R$ 339,04<\/td>\r\n<td>R$ 372,57<\/td>\r\n<td>R$ 383,75<\/td>\r\n<td>R$ 413,55<\/td>\r\n<td>R$ 819,67<\/td>\r\n<td>R$ 953,79<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>29 a 33 anos<\/td>\r\n<td>R$ 382,43<\/td>\r\n<td>R$ 424,93<\/td>\r\n<td>R$ 406,85<\/td>\r\n<td>R$ 447,09<\/td>\r\n<td>R$ 460,50<\/td>\r\n<td>R$ 496,26<\/td>\r\n<td>R$ 983,60<\/td>\r\n<td>R$ 1.144,54<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>34 a 38 anos<\/td>\r\n<td>R$ 435,98<\/td>\r\n<td>R$ 484,42<\/td>\r\n<td>R$ 463,81<\/td>\r\n<td>R$ 509,68<\/td>\r\n<td>R$ 524,97<\/td>\r\n<td>R$ 565,75<\/td>\r\n<td>R$ 1.121,30<\/td>\r\n<td>R$ 1.304,78<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>39 a 43 anos<\/td>\r\n<td>R$ 449,06<\/td>\r\n<td>R$ 498,96<\/td>\r\n<td>R$ 477,72<\/td>\r\n<td>R$ 524,97<\/td>\r\n<td>R$ 540,72<\/td>\r\n<td>R$ 582,72<\/td>\r\n<td>R$ 1.154,94<\/td>\r\n<td>R$ 1.343,93<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>44 a 48 anos<\/td>\r\n<td>R$ 546,75<\/td>\r\n<td>R$ 607,50<\/td>\r\n<td>R$ 581,65<\/td>\r\n<td>R$ 639,17<\/td>\r\n<td>R$ 658,35<\/td>\r\n<td>R$ 709,49<\/td>\r\n<td>R$ 1.406,20<\/td>\r\n<td>R$ 1.636,30<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>49 a 53 anos<\/td>\r\n<td>R$ 643,09<\/td>\r\n<td>R$ 714,55<\/td>\r\n<td>R$ 684,14<\/td>\r\n<td>R$ 751,81<\/td>\r\n<td>R$ 774,36<\/td>\r\n<td>R$ 834,50<\/td>\r\n<td>R$ 1.653,97<\/td>\r\n<td>R$ 1.924,62<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>54 a 58 anos<\/td>\r\n<td>R$ 765,28<\/td>\r\n<td>R$ 850,31<\/td>\r\n<td>R$ 814,13<\/td>\r\n<td>R$ 894,65<\/td>\r\n<td>R$ 921,49<\/td>\r\n<td>R$ 993,06<\/td>\r\n<td>R$ 1.968,23<\/td>\r\n<td>R$ 2.290,30<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>+ de 59 anos<\/td>\r\n<td>R$ 1.339,25<\/td>\r\n<td>R$ 1.488,05<\/td>\r\n<td>R$ 1.424,73<\/td>\r\n<td>R$ 1.565,63<\/td>\r\n<td>R$ 1.612,60<\/td>\r\n<td>R$ 1.737,86<\/td>\r\n<td>R$ 3.444,39<\/td>\r\n<td>R$ 4.008,02<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<\/div>\n<div class=\"panel entry-content\" id=\"tab_estado-rj\">\r\n<div class=\"ta-c\"><b>TABELA BRADESCO SA\u00daDE EMPRESARIAL RJ COMPULS\u00d3RIO<\/b><\/div>\r\n<div><\/div>\r\n<div class=\"ta-c\">Taxa de Inscri\u00e7\u00e3o: (Por Contrato) - R$ 7,50 por vida, acrescentar IOF de 2,38% sobre o valor total final<\/div>\r\n<table class=\"static small ta-c\">\r\n<tbody>\r\n<tr class=\"bgGray\">\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">Faixa Et\u00e1ria<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">FLEX (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">FLEX (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TPE (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TPQ (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNE (E)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNQ (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TQN2 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TQN3 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNP4 (A)<\/span><\/strong><\/td>\r\n<td style=\"background-color: #a31010;\"><strong><span style=\"color: #fafafa;\">TNP6 (A)<\/span><\/strong><\/td>\r\n<\/tr>\r\n<tr>\r\n<td>0 a 18 anos<\/td>\r\n<td>R$ 226,62<\/td>\r\n<td>R$ 251,81<\/td>\r\n<td>R$ 234,27<\/td>\r\n<td>R$ 266,21<\/td>\r\n<td>R$ 254,63<\/td>\r\n<td>R$ 289,35<\/td>\r\n<td>R$ 298,04<\/td>\r\n<td>R$ 321,19<\/td>\r\n<td>R$ 636,60<\/td>\r\n<td>R$ 740,77<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>19 a 23 anos<\/td>\r\n<td>R$ 267,41<\/td>\r\n<td>R$ 297,13<\/td>\r\n<td>R$ 276,43<\/td>\r\n<td>R$ 314,13<\/td>\r\n<td>R$ 300,47<\/td>\r\n<td>R$ 341,44<\/td>\r\n<td>R$ 351,69<\/td>\r\n<td>R$ 379,01<\/td>\r\n<td>R$ 751,18<\/td>\r\n<td>R$ 874,10<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>24 a 28 anos<\/td>\r\n<td>R$ 323,57<\/td>\r\n<td>R$ 359,53<\/td>\r\n<td>R$ 334,48<\/td>\r\n<td>R$ 380,10<\/td>\r\n<td>R$ 363,57<\/td>\r\n<td>R$ 413,14<\/td>\r\n<td>R$ 425,54<\/td>\r\n<td>R$ 458,59<\/td>\r\n<td>R$ 908,93<\/td>\r\n<td>R$ 1.057,66<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>29 a 33 anos<\/td>\r\n<td>R$ 388,29<\/td>\r\n<td>R$ 431,43<\/td>\r\n<td>R$ 401,38<\/td>\r\n<td>R$ 456,11<\/td>\r\n<td>R$ 436,28<\/td>\r\n<td>R$ 495,78<\/td>\r\n<td>R$ 510,65<\/td>\r\n<td>R$ 550,31<\/td>\r\n<td>R$ 1.090,71<\/td>\r\n<td>R$ 1.269,20<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>34 a 38 anos<\/td>\r\n<td>R$ 442,65<\/td>\r\n<td>R$ 491,84<\/td>\r\n<td>R$ 457,57<\/td>\r\n<td>R$ 519,98<\/td>\r\n<td>R$ 497,36<\/td>\r\n<td>R$ 565,18<\/td>\r\n<td>R$ 582,14<\/td>\r\n<td>R$ 627,36<\/td>\r\n<td>R$ 1.243,41<\/td>\r\n<td>R$ 1.446,89<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>39 a 43 anos<\/td>\r\n<td>R$ 455,94<\/td>\r\n<td>R$ 506,59<\/td>\r\n<td>R$ 471,30<\/td>\r\n<td>R$ 535,57<\/td>\r\n<td>R$ 512,28<\/td>\r\n<td>R$ 582,14<\/td>\r\n<td>R$ 599,61<\/td>\r\n<td>R$ 646,18<\/td>\r\n<td>R$ 1.280,72<\/td>\r\n<td>R$ 1.490,29<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>44 a 48 anos<\/td>\r\n<td>R$ 555,12<\/td>\r\n<td>R$ 616,81<\/td>\r\n<td>R$ 573,84<\/td>\r\n<td>R$ 652,08<\/td>\r\n<td>R$ 623,74<\/td>\r\n<td>R$ 708,79<\/td>\r\n<td>R$ 730,05<\/td>\r\n<td>R$ 786,76<\/td>\r\n<td>R$ 1.559,34<\/td>\r\n<td>R$ 1.814,51<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>49 a 53 anos<\/td>\r\n<td>R$ 652,93<\/td>\r\n<td>R$ 725,49<\/td>\r\n<td>R$ 674,94<\/td>\r\n<td>R$ 766,98<\/td>\r\n<td>R$ 733,64<\/td>\r\n<td>R$ 833,68<\/td>\r\n<td>R$ 858,70<\/td>\r\n<td>R$ 925,39<\/td>\r\n<td>R$ 1.834,10<\/td>\r\n<td>R$ 2.134,23<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>54 a 58 anos<\/td>\r\n<td>R$ 776,99<\/td>\r\n<td>R$ 863,33<\/td>\r\n<td>R$ 803,19<\/td>\r\n<td>R$ 912,71<\/td>\r\n<td>R$ 873,03<\/td>\r\n<td>R$ 992,08<\/td>\r\n<td>R$ 1.021,84<\/td>\r\n<td>R$ 1.101,21<\/td>\r\n<td>R$ 2.182,58<\/td>\r\n<td>R$ 2.539,73<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>+ de 59 anos<\/td>\r\n<td>R$ 1.359,75<\/td>\r\n<td>R$ 1.510,83<\/td>\r\n<td>R$ 1.405,58<\/td>\r\n<td>R$ 1.597,25<\/td>\r\n<td>R$ 1.527,81<\/td>\r\n<td>R$ 1.736,14<\/td>\r\n<td>R$ 1.788,23<\/td>\r\n<td>R$ 1.927,12<\/td>\r\n<td>R$ 3.819,52<\/td>\r\n<td>R$ 4.444,53<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<\/div><\/div><\/div>\n\t\t<\/div>\n\t\t\n<style>\n#col-329286502 > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\n<style>\n#col-1449642972 > .col-inner {\n  margin: 0px 0px -50px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-722747078\">\n\n\t<div id=\"col-1994924515\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2><span style=\"color: #a60707;\">Rede Credenciada Bradesco Sa\u00fade<\/span><\/h2>\n<p>O Bradesco Sa\u00fade oferece os melhores hospitais, laborat\u00f3rios e m\u00e9dicos do Brasil. O desempenho de uma grande seguradora como a Bradesco Sa\u00fade \u00e9 visto com sucesso n\u00e3o somente com a cura de doen\u00e7as, mas sim quando a seguradora trabalha junto com o seu segurado para evitar que problemas de sa\u00fade eventualmente ocorram. O Bradesco Sa\u00fade trabalha dessa maneira, o que lhe rendeu credibilidade e confian\u00e7a ao longo de sua trajet\u00f3ria no mercado de seguro sa\u00fade.<\/p>\n<p>A Rede do <strong>Plano de Sa\u00fade Bradesco<\/strong> vai al\u00e9m de nomes de hospitais renomados, profissionais e laborat\u00f3rios de alta qualidade, Com o objetivo de sempre facilitar o dia a dia dos seus segurados, a Bradesco Sa\u00fade disponibilizou para download a vers\u00e3o atualizada do seu aplicativo, oferecendo novas funcionalidades, tais como: consultar reembolso, localizar referenciados, visualizar o cart\u00e3o de identifica\u00e7\u00e3o online \u2013 por interm\u00e9dio do aplicativo Carteira Digital, localizar farm\u00e1cias pr\u00f3ximas, 2\u00aa via do extrato de IR, al\u00e9m de criar a carteira de vacina\u00e7\u00e3o e acessar o calend\u00e1rio de vacinas.<\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-1994924515 > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1297776840\">\n\n\t<div id=\"col-1728500348\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-194298485\">\n\n\t<div id=\"col-1124548855\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 80%;\"><strong>S\u00e3o Paulo &#8211; Zona Central<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. 9 DE JULHO &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. A.C. CAMARGO &#8211; H<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. ALEM\u00c3O OSWALDO CRUZ &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP ALEMAO OSWALDO CRUZ &#8211; UNIDADE VERGUEIRO &#8211; H<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL BENEFIC\u00caNCIA PORTUGUESA &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL E MATERNIDADE SANTA JOANA &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL INFANTIL SABAR\u00c1 &#8211; H\/ PS &#8211; Atendimento somente para acomoda\u00e7\u00e3o quarto<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL LEFORTE LIBERDADE &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL SAHA &#8211; H<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL SAMARITANO &#8211; H\/ M\/ PS &#8211; Atendimento somente para acomoda\u00e7\u00e3o quarto<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL SANTA CATARINA &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. PAULISTANO &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. SANTA ISABEL &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. S\u00cdRIO LIBAN\u00caS &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">PRO MATRE PAULISTA &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>S\u00e3o Paulo &#8211; Zona Sul<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. ALVORADA &#8211; MOEMA &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. ALVORADA SANTO AMARO &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. DA AACD &#8211; H<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. DO RIM E HIPERTENS\u00c3O &#8211; H<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. E MATERNIDADE VIDAS 1 &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. E MAT. S\u00c3O LUIZ &#8211; (ITAIM) &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. E MAT. S\u00c3O LUIZ &#8211; (JABAQUARA) &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL DA CRIANCA &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL DO CORA\u00c7\u00c3O &#8211; HCOR &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL PAULISTA DE ORL &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL SANTA CRUZ &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL SANTA PAULA &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL SANTA RITA &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL S\u00c3O CAMILO &#8211; IPIRANGA &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL SERRA MAYOR &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP PROF. EDMUNDO VASCONCELOS &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">IOP INST. DE ONCOLOGIA PEDI\u00c1TRICA &#8211; H<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL E MATERNIDADE SEPACO &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>S\u00e3o Paulo &#8211; Zona Leste<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">DAY HOSPITAL DE ERMELINO MATARAZZO &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. CENTRAL DE GUAIANASES &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. E MAT. S\u00c3O LUIZ &#8211; (AN\u00c1LIA FRANCO) &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. INDEPENDENCIA &#8211; H<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL VILLA LOBOS &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. SANTA MARCELINA &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. SANTA VIRGINIA &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">IBCC ( MOOCA) &#8211; H<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>S\u00e3o Paulo &#8211; Zona Norte<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL S\u00c3O CAMILO &#8211; SANTANA &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. NIPO BRASILEIRO &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>S\u00e3o Paulo &#8211; Zona Oeste<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. E MAT. S\u00c3O LUIZ &#8211; (MORUMBI) &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. ISRAELITA ALBERT EINSTEIN &#8211; H\/ M\/ PS &#8211; Quarto<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL ALBERT SABIN &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL DAS CL\u00cdNICAS &#8211; FMUSP &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL E PRONTO SOCORRO PORTINARI &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL LEFORTE (MORUMBI) &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL METROPOLITANO LAPA &#8211; H\/ M\/ PS<\/span><\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-1124548855 > .col-inner {\n  padding: 5px 5px 5px 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1965687824\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 80%;\">HOSPITAL S\u00c3O CAMILO &#8211; POMPEIA &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">INCOR &#8211; INSTITUTO DO CORA\u00c7\u00c3O &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>S\u00e3o Paulo &#8211; V\u00e1rias Regi\u00f5es<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">CEMA HOSP. ESPECILIZADO &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL DOS DEFEITOS DA FACE &#8211; H<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Barueri &#8211; Outras Regi\u00f5es<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITALIS &#8211; N\u00daCLEO HOSPITALAR DE BARUERI &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Carapicu\u00edba &#8211; Outras Regi\u00f5es<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. ALPHA MED &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Osasco &#8211; Outras Regi\u00f5es<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP CRUZEIRO DO SUL &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL E MATERNIDADE SINO BRASILEIRO &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL N. SRA. DE F\u00c1TIMA &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Cotia &#8211; Outras Regi\u00f5es<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">CENTRO MEDICO SAO FRANCISCO &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Itapevi &#8211; Outras Regi\u00f5es<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL E MATERNIDADE NOVA VIDA &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Guarulhos &#8211; Outras Regi\u00f5es<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. BOM CLIMA &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL CARLOS CHAGAS &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Caieiras &#8211; Outras Regi\u00f5es<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL DE CLINICAS CAIEIRAS &#8211; H\/ M<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Tabo\u00e3o da Serra &#8211; Outras Regi\u00f5es<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL FAMILY &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">POLICL\u00cdNICA TABO\u00c3O &#8211; &#8211;<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Santo Andr\u00e9 &#8211; ABCDM<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. ABC &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. BENEF. PORTUGUESA DE SANTO ANDR\u00c9 &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL E MAT. BARTIRA &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL E MATERNIDADE BRASIL &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL E MATERNIDADE DR CHRISTOVAO DA GAMA &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>S\u00e3o Bernardo do Campo &#8211; ABCDM<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">CENTRO DE TRATAMENTO BEZERRA DE MENEZES &#8211; H<\/span><br \/>\n<span style=\"font-size: 80%;\">CLINICA VAAD &#8211; H<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. IFOR SC LTDA &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL E MATERNIDADE ASSUN\u00c7AO &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL E MATERNIDADE ITACOLOMY &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL S\u00c3O BERNARDO &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL S\u00c3O BERNARDO (UNIDADE BAETA NEVES) &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>S\u00e3o Caetano do Sul &#8211; ABCDM<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL E MATERNIDADE CENTRAL &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL NOSSA SENHORA DE F\u00c1TIMA &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL S\u00c3O LUIZ &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Diadema &#8211; ABCDM<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">INNOVA HOSPITAIS ASSOCIADOS &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Mau\u00e1 &#8211; ABCDM<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. AM\u00c9RICA &#8211; H\/ M<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Ribeir\u00e3o Pires &#8211; ABCDM<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL E MATERNIDADE RIBEIR\u00c3O PIRES &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Aruj\u00e1 &#8211; Outras Regi\u00f5es<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL E MATERNIDADE IPIRANGA &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Mogi das Cruzes &#8211; Outras Regi\u00f5es<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP E MATER MOGI MATER &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. IPIRANGA DE MOGI DAS CRUZES &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL SANTANA &#8211; H\/ M\/ PS<\/span><\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-1965687824 > .col-inner {\n  padding: 5px 5px 5px 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-346303833\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 80%;\"><strong>Santos &#8211; Litoral<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL ANA COSTA &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. SAO LUCAS &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Americana &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL SAO FRANCISCO DE AMERICANA &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Campinas &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL E MATERNIDADE CELSO PIERRO &#8211; H\/ M<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL MADRE THEODORA CAMPINAS &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL SANTA TEREZA &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL VERA CRUZ &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL RENASCENCA CAMPINAS &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Franca &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL E MATERNIDADE S\u00c3O JOAQUIM &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. REGIONAL DE FRANCA S A &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Lorena &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">SANTA CASA DE MISERIC. DE LORENA &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Presidente Prudente &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL GERAL IAMADA &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. NOSSA SENHORA DAS GRA\u00c7AS &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">STA. CASA DE MISER. PRESIDENTE PRUDENTE &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Ribeir\u00e3o Preto &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">CL CIVIL H C RIBEIRAO PRETO &#8211; H\/ M<\/span><br \/>\n<span style=\"font-size: 80%;\">STA. CASA DE MISERIC. DE RIBEIR\u00c3O PRETO &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Rio Claro &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL SANTA FILOMENA &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL S\u00c3O RAFAEL &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>S\u00e3o Jos\u00e9 dos Campos &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL E MATERNIDADE POLICLIN &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL VIVALLE &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>S\u00e3o Jos\u00e9 dos Campos &#8211; Outras Regi\u00f5es<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. SAO JOSE &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Sorocaba &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">FUND. S\u00c3O PAULO HOSP. SANTA LUCINDA &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL EVANGELICO &#8211; H<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL SAMARITANO SOROCABA &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Atibaia &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL NOVO ATIBAIA &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Barretos &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL S\u00c3O JORGE &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">SANTA CASA DE MISERIC\u00d3RDIA DE BARRETOS &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Bragan\u00e7a Paulista &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL UNIVERSITARIO S\u00c3O FRANCISCO &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Indaiatuba &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL SANTA IGNES &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Jacare\u00ed &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL S\u00c3O FRANCISCO DE ASSIS &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Jundia\u00ed &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">SOBAM CTO MED PITANGUEIRAS &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Jundia\u00ed &#8211; Outras Regi\u00f5es<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL PAULO SACRAMENTO &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\">HOSPITAL SANTA ELISA &#8211; H\/ M\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Taubat\u00e9 &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">HOSP. REGIONAL DO VALE DO PARA\u00cdBA &#8211; H\/ PS<\/span><br \/>\n<span style=\"font-size: 80%;\"><strong>Valinhos &#8211; Interior<\/strong><\/span><br \/>\n<span style=\"font-size: 80%;\">IRM. SANTA CASA DE MISERIC\u00d3RDIA DE VALINHOS &#8211; H\/ M\/ PS<\/span><\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-346303833 > .col-inner {\n  padding: 5px 5px 5px 5px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1199061144\">\n\n\t<div id=\"col-541299726\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<table class=\"static small\">\n<tbody>\n<tr class=\"bgGray\">\n<td class=\"ta-l\"><strong><span style=\"font-size: 110%;\">Legendas<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"ta-l\"><span style=\"font-size: 110%;\">H &#8211; Interna\u00e7\u00e3o Eletiva, PS &#8211; Pronto Socorro, M &#8211; Maternidade<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t<\/div>\n\t\t\n<style>\n#col-541299726 > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<h2><span style=\"color: #a60707;\">Diferencias Bradesco Sa\u00fade<\/span><\/h2>\n<p>As Empresas poder\u00e3o contratar coberturas adicionais n\u00e3o contempladas\u00a0no Rol de Procedimentos e Eventos em Sa\u00fade, editado pela Ag\u00eancia\u00a0Nacional de Sa\u00fade Suplementar (ANS).<\/p>\n<div class=\"row\"  id=\"row-184824991\">\n\n\t<div id=\"col-1184332645\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-circle-o \" ><\/i><\/span>\u00a0<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/diferenciais\/\" target=\"_blank\" rel=\"noopener noreferrer\">Livre Escolha de Prestadores<\/a><\/p>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-circle-o \" ><\/i><\/span>\u00a0<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/diferenciais\/\" target=\"_blank\" rel=\"noopener noreferrer\">Kit Digital<\/a><\/p>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-circle-o \" ><\/i><\/span>\u00a0<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/diferenciais\/\" target=\"_blank\" rel=\"noopener noreferrer\">Meu Doutor Bradesco Sa\u00fade<\/a><\/p>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-circle-o \" ><\/i><\/span>\u00a0<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/diferenciais\/\" target=\"_blank\" rel=\"noopener noreferrer\">Segunda Opini\u00e3o M\u00e9dica<\/a><\/p>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-circle-o \" ><\/i><\/span>\u00a0<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/diferenciais\/\" target=\"_blank\" rel=\"noopener noreferrer\">Contrata\u00e7\u00e3o Conjugada ao Plano Odontol\u00f3gico<\/a><\/p>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-circle-o \" ><\/i><\/span>\u00a0<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/diferenciais\/\" target=\"_blank\" rel=\"noopener noreferrer\">Sistema de Informa\u00e7\u00f5es Gerenciais &#8211; SIGE<\/a><\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-473647753\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-circle-o \" ><\/i><\/span>\u00a0<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/diferenciais\/\" target=\"_blank\" rel=\"noopener noreferrer\">Assist\u00eancia em Viagem<\/a><\/p>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-circle-o \" ><\/i><\/span>\u00a0<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/diferenciais\/\" target=\"_blank\" rel=\"noopener noreferrer\">Clube de Vantagens<\/a><\/p>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-circle-o \" ><\/i><\/span>\u00a0<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/diferenciais\/\" target=\"_blank\" rel=\"noopener noreferrer\">Certifica\u00e7\u00e3o no Processo de Bahiadita\u00e7\u00e3o no Brasil<\/a><\/p>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-circle-o \" ><\/i><\/span>\u00a0<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/diferenciais\/\" target=\"_blank\" rel=\"noopener noreferrer\">Desconto Farm\u00e1cia*<\/a><\/p>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-circle-o \" ><\/i><\/span>\u00a0<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/diferenciais\/\" target=\"_blank\" rel=\"noopener noreferrer\">Bradesco Sa\u00fade Concierge<\/a><\/p>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-circle-o \" ><\/i><\/span>\u00a0<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/diferenciais\/\" target=\"_blank\" rel=\"noopener noreferrer\">Aplicativo Legisla\u00e7\u00e3o de Sa\u00fade Suplementar para iPad<\/a><\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\n<style>\n#col-1728500348 > .col-inner {\n  padding: 10px 10px 10px 10px;\n  margin: 0px 0px -54px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1000979502\">\n\n\t<div id=\"col-1363976020\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 115%;\">Para ter acesso a todos os diferencias oferecidos pelo plano Bradesco Sa\u00fade\u00a0<strong><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/diferenciais\/\">Clique Aqui<\/a><\/strong><\/span><\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-713247932\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-713247932 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-21789703\">\n\n\t<div id=\"col-498030951\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2><span style=\"color: #a60707;\">Documentos Para Contra\u00e7\u00e3o Plano de Sa\u00fade Bradesco Empresarial<\/span><\/h2>\n<p>Abaixo documentos necess\u00e1rios para emiss\u00e3o ap\u00f3lice Bradesco sa\u00fade, Ap\u00f3s o envio de toda a documenta\u00e7\u00e3o ser\u00e1 gerado a proposta com numero de ap\u00f3lice e boleto com vencimento de at\u00e9 60 dias, dessa forma o benefici\u00e1rio pode escolher a melhor data de pagamento e ativa\u00e7\u00e3o do plano. O numero de carteirinha ser\u00e1 gerado ap\u00f3s 48 horas da quita\u00e7\u00e3o do primeiro boleto e os demais vencimentos ser\u00e1 sempre no dia do primeiro pagamento todos os meses.<\/p>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-arrow-circle-right \" ><\/i><\/span>\u00a0Contrato Social ou Contrato de empresa Individual<\/p>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-arrow-circle-right \" ><\/i><\/span>\u00a0Cart\u00e3o CNPJ<\/p>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-arrow-circle-right \" ><\/i><\/span>\u00a0Quando houver funcion\u00e1rios \u2013 Rela\u00e7\u00e3o do FGTS, (quando o funcion\u00e1rio tiver admiss\u00e3o inferior a 30 dias, entregar c\u00f3pia da Carteira Profissional ou do Livro de Registro.<\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-498030951 > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-2106759790\">\n\n\t<div id=\"col-358810358\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3>Benefici\u00e1rio Titular<\/h3>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-arrow-circle-right \" ><\/i><\/span>\u00a0Diretores estatut\u00e1rios, s\u00f3cios com poderes de Gest\u00e3o e administradores;<br \/>\n<span style=\"color: #ed1c24;\"><i class=\"fa fa-arrow-circle-right \" ><\/i><\/span>\u00a0Empregados;<br \/>\n<span style=\"color: #ed1c24;\"><i class=\"fa fa-arrow-circle-right \" ><\/i><\/span>\u00a0Estagi\u00e1rios;<br \/>\n<span style=\"color: #ed1c24;\"><i class=\"fa fa-arrow-circle-right \" ><\/i><\/span>\u00a0Menores Aprendizes com idade entre 14 e 24 anos;<br \/>\n<span style=\"color: #ed1c24;\"><i class=\"fa fa-arrow-circle-right \" ><\/i><\/span>\u00a0Expatriados\/Estrangeiros;<br \/>\n<span style=\"color: #ed1c24;\"><i class=\"fa fa-arrow-circle-right \" ><\/i><\/span>\u00a0Afastados;<br \/>\n<span style=\"color: #ed1c24;\"><i class=\"fa fa-arrow-circle-right \" ><\/i>\u00a0<\/span>Demitidos e aposentados: conforme a Resolu\u00e7\u00e3o Normativa n\u00ba 195, da ANS.<\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-358810358 > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1760046257\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3>Benefici\u00e1rio Dependente<\/h3>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-arrow-circle-right \" ><\/i>\u00a0<\/span>C\u00f4njuge;<br \/>\n<span style=\"color: #ed1c24;\"><i class=\"fa fa-arrow-circle-right \" ><\/i>\u00a0<\/span>Companheiro(a): havendo uni\u00e3o est\u00e1vel na forma da lei, sem concorr\u00eancia com o c\u00f4njuge;<br \/>\n<span style=\"color: #ed1c24;\"><i class=\"fa fa-arrow-circle-right \" ><\/i><\/span>\u00a0Filhos: solteiros (naturais, adotivos ou enteados) com at\u00e9 29 anos;<br \/>\n<span style=\"color: #ed1c24;\"><i class=\"fa fa-arrow-circle-right \" ><\/i><\/span>\u00a0Filhos inv\u00e1lidos de qualquer idade, assim considerados aqueles eleg\u00edveis para efeito da Declara\u00e7\u00e3o de Imposto de Renda do Benefici\u00e1rio titular.<\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-1760046257 > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-34611015\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-34611015 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-508765937\">\n\n\t<div id=\"col-1651937283\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2><span style=\"color: #a60707;\">Acomoda\u00e7\u00e3o Bradesco Sa\u00fade<\/span><\/h2>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1396520910\">\n\n\t<div id=\"col-445174315\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1344439391\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"216\" height=\"164\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2018\/06\/Acomoda\u00e7\u00e3o-Bradesco-Sa\u00fade.png\" class=\"attachment-large size-large\" alt=\"Acomoda\u00e7\u00e3o Bradesco Sa\u00fade\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1344439391 {\n  width: 85%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-77096262\" class=\"col medium-8 small-12 large-8\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 115%;\">A Bradesco Sa\u00fade disponibiliza dois padr\u00f5es de acomoda\u00e7\u00e3o hospitalar:<\/span><\/p>\n<p><span style=\"font-size: 115%;\">\u2022 Quarto individual, Apenas uma pessoa por quarto.<\/span><br \/>\n<span style=\"font-size: 115%;\">(para todos os planos);<\/span><\/p>\n<p><span style=\"font-size: 115%;\">\u2022 Enfermaria, acomoda\u00e7\u00e3o para 2 pessoas por quarto<\/span><br \/>\n<span style=\"font-size: 115%;\">(exceto para o Premium e o Nacional Plus).<\/span><\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-77096262 > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-882551185\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-882551185 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1649951781\">\n\n\t<div id=\"col-411404862\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"message-box relative dark\" style=\"padding-top:15px;padding-bottom:15px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgb(36, 18, 245);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\n<div class=\"row align-middle align-center\"  id=\"row-1742309274\">\n\n\t<div id=\"col-949107128\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 140%;\">A NF Corretora de Seguros\u00a0est\u00e1 oferecendo uma <strong>Promo\u00e7\u00e3o de at\u00e9 50% de desconto na primeira parcela<\/strong> dependendo da categoria do plano Bradesco Sa\u00fade escolhida.\u00a0<strong><a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/orcamento\/\" target=\"_blank\" rel=\"noopener noreferrer\">Confira!<\/a><\/strong><\/span><\/p>\n\t<div id=\"gap-1337453015\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1337453015 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/contato\/\" target=\"_self\" class=\"button white is-outline reveal-icon\"  style=\"border-radius:9px;\">\n    <span>Cota\u00e7\u00e3o Bradesco Sa\u00fade<\/span>\n  <i class=\"icon-checkmark\" ><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<\/div><\/div><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-2140128415\">\n\n\t<div id=\"col-426256141\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2><span style=\"color: #a60707;\">Reembolso Plano de Sa\u00fade Bradesco<\/span><\/h2>\n<p>O Benefici\u00e1rio que contratar o plano Bradesco Sa\u00fade com CNPJ poder\u00e1 utilizar qualquer servi\u00e7o que esteja coberto pelo Seguro-sa\u00fade com um prestador de sua livre escolha que n\u00e3o fa\u00e7a parte da Lista de Refer\u00eancia, desde que sejam respeitados a \u00e1rea de atua\u00e7\u00e3o do produto e os limites contratados.<\/p>\n<p>A Bradesco Sa\u00fade ira fazer a analise da documenta\u00e7\u00e3o enviada pelo segurado e processamento do reembolso, conforme as coberturas e limites contratuais do seguro, inclusive nos casos de urg\u00eancia e emerg\u00eancia, contados a partir do recebimento, pela Operadora, de toda a documenta\u00e7\u00e3o relacionada no item Documenta\u00e7\u00e3o Necess\u00e1ria para Solicita\u00e7\u00e3o de Reembolso, de acordo com o procedimento realizado.<\/p>\n<p>O pagamento do valor a ser reembolsado ser\u00e1 efetuado diretamente na conta corrente do Benefici\u00e1rio titular. Para que o reembolso seja efetuado com seguran\u00e7a, \u00e9 importante que os dados da conta corrente do Benefici\u00e1rio estejam sempre atualizado junto ao cadastro do benefici\u00e1rio.<\/p>\n<p>Documenta\u00e7\u00e3o Necess\u00e1ria para Solicita\u00e7\u00e3o de Reembolso:<\/p>\n<p>O Benefici\u00e1rio dever\u00e1 observar o prazo m\u00e1ximo de 1 (um) ano, a partir da data de ocorr\u00eancia do evento, para apresenta\u00e7\u00e3o dos pedidos de reembolso. Para o efetivo reembolso, o Benefici\u00e1rio dever\u00e1 apresentar toda a documenta\u00e7\u00e3o relacionada no formul\u00e1rio denominado Envelope para Solicita\u00e7\u00e3o de Reembolso, o qual dever\u00e1 ser devidamente preenchido com os dados cadastrais do Benefici\u00e1rio Titular.<\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1107143103\">\n\n\t<div id=\"col-1531846873\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\" style=\"background-color:rgb(254, 252, 252);\" >\n\t\t\t\n\t\t\t\n<h2><span style=\"color: #a60707;\">Duvidas Plano de Sa\u00fade Bradesco<\/span><\/h2>\n<div class=\"accordion\" rel=\"\">\n<div class=\"accordion-item\"><a href=\"#\" class=\"accordion-title plain\"><button class=\"toggle\"><i class=\"icon-angle-down\"><\/i><\/button><span>Qual \u00e9 o Telefone de Contato Bradesco Sa\u00fade Empresarial?<\/span><\/a><div class=\"accordion-inner\">\n<h3>Central de\u00a0Vendas Bradesco Sa\u00fade:<\/h3>\n<p>Grupo de corretores treinados para\u00a0 tiras todas as duvidas, por telefone ou pelo chat online. Receba cota\u00e7\u00e3o por e-mail com tabela de valores e rede credenciada de hospitais credenciados. Fa\u00e7a seu plano de sa\u00fade Bradesco com 50% Desconto, ligando nos telefones abaixo.<\/p>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-square-o \" ><\/i><\/span> (11) 2801-6163 (capitais e regi\u00f5es metropolitanas)<\/p>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-square-o \" ><\/i><\/span> (11) 2801-6163 (demais localidades)<\/p>\n<p><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-square-o \" ><\/i><\/span> (11) 99334-3454 (Atendimento WhatsApp)<\/p>\n<h3>J\u00e1 sou Cliente Bradesco Sa\u00fade<\/h3>\n<p><strong>Consultar Rede Credenciada<\/strong><\/p>\n<p><strong>2\u00ba Via de Boleto<\/strong><\/p>\n<p><strong>Atendimento ao Cliente<\/strong><\/p>\n<p><strong><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-square-o \" ><\/i> <\/span>4004 2761 (capitais e regi\u00f5es metropolitanas)<\/strong><\/p>\n<p><strong><span style=\"color: #ed1c24;\"><i class=\"fa fa-check-square-o \" ><\/i> <\/span>0800 701 2761 (demais localidades)<\/strong><\/p>\n<\/div><\/div>\n<div class=\"accordion-item\"><a href=\"#\" class=\"accordion-title plain\"><button class=\"toggle\"><i class=\"icon-angle-down\"><\/i><\/button><span>Qual \u00e9 o Prazo de vigencia do Contrato Bradesco Sa\u00fade Empresarial?<\/span><\/a><div class=\"accordion-inner\">\n<p>A vig\u00eancia inicial do contrato \u00e9 de 24 meses, contados a partir da data definida na proposta assinada pela empresa contratante.<\/p>\n<\/div><\/div>\n<div class=\"accordion-item\"><a href=\"#\" class=\"accordion-title plain\"><button class=\"toggle\"><i class=\"icon-angle-down\"><\/i><\/button><span>Todos os colaboradores precisam aderir ao plano de sa\u00fade?<\/span><\/a><div class=\"accordion-inner\">\n<p>na\u00a0 modalidade Compuls\u00f3ria \u00e9 necess\u00e1rio incluir todo o grupo que esta na empresa. Esta op\u00e7\u00e3o \u00e9 v\u00e1lida para os titulares e todos os seus dependentes. J\u00e1 na modalidade Opcional n\u00e3o h\u00e1 obrigatoriedade de inclus\u00e3o de todo o grupo vinculado \u00e0 empresa.<\/p>\n<\/div><\/div>\n<div class=\"accordion-item\"><a href=\"#\" class=\"accordion-title plain\"><button class=\"toggle\"><i class=\"icon-angle-down\"><\/i><\/button><span>Caso o benefici\u00e1rio seja atendido por um m\u00e9dico particular, como dever\u00e1 proceder?<\/span><\/a><div class=\"accordion-inner\">\n<p>O colaborador poder\u00e1 realizar qualquer procedimento coberto, desde que sejam respeitadas as condi\u00e7\u00f5es contratuais. Basta escolher o profissional de interesse, pagar pelos servi\u00e7os utilizados, solicitar o recibo de pagamento e apresentar \u00e0 Bradesco Sa\u00fade para reembolso. O reembolso ser\u00e1 realizado de acordo com os limites estabelecidos no plano contratado como informado no site acima. O prazo para o pagamento do reembolso \u00e9 de at\u00e9 30 dias ap\u00f3s o recebimento da documenta\u00e7\u00e3o completa.<\/p>\n<\/div><\/div>\n<div class=\"accordion-item\"><a href=\"#\" class=\"accordion-title plain\"><button class=\"toggle\"><i class=\"icon-angle-down\"><\/i><\/button><span>No dia da consulta, o benefici\u00e1rio dever\u00e1 apresentar alguma autoriza\u00e7\u00e3o especial?<\/span><\/a><div class=\"accordion-inner\">\n<p>N\u00e3o. O benefici\u00e1rio dever\u00e1 apresentar sua carteirinha, f\u00edsica ou virtual dispon\u00edvel atrav\u00e9s do <a href=\"https:\/\/apps.apple.com\/br\/app\/bradesco-seguros\/id1256508403\" target=\"_blank\" rel=\"noopener noreferrer\">aplicativo Bradesco seguros<\/a> e um documento oficial com foto.<\/p>\n<\/div><\/div>\n<\/div>\n\t\t<\/div>\n\t\t\n<style>\n#col-1531846873 > .col-inner {\n  padding: 20px 20px 20px 20px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-2107677495\">\n\n\t<div id=\"col-26770610\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_517306650\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"658\" height=\"941\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/01\/cota\u00e7\u00e3o-Online-Bradesco-Sa\u00fade.png\" class=\"attachment-large size-large\" alt=\"cota\u00e7\u00e3o Online Bradesco Sa\u00fade\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/01\/cota\u00e7\u00e3o-Online-Bradesco-Sa\u00fade.png 658w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/01\/cota\u00e7\u00e3o-Online-Bradesco-Sa\u00fade-210x300.png 210w\" sizes=\"auto, (max-width: 658px) 100vw, 658px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_517306650 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1604468684\" class=\"col medium-8 small-12 large-8\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2><span style=\"color: #a60707;\">Cota\u00e7\u00e3o Online Bradesco Sa\u00fade<\/span><\/h2>\n<div data-uniq='6a04dadc0002a' class='uniq-6a04dadc0002a formcraft-css form-live align-center'><style type='text\/css' scoped='scoped'>.zopim { display:none !important;}\n.heading-cover  { DISPLAY:NONE !IMPORTANT;}\nhtml .formcraft-css .fc-form .form-element .form-element-html {\n    padding: 1.5em 1.5em;\n    padding-left: 0;\n    padding-top: 0;\n    margin-top: -10px;\nbackground:transparent !important;\n}\nhtml .formcraft-css .fc-form .field-cover>span>span {\n    display: block;\n    width: 100%;\n    line-height: 1.45em;\n    font-weight: 600;\n    font-size: 17px;\n}\n.select2-container.select2-container--default .select2-selection--single {\n    -webkit-border-radius: 0;\n    -moz-border-radius: 0;\n    -ms-border-radius: 0;\n    border-radius: 0;\n    border: 1px solid #cacaca;\n    height: 40px;\n    line-height: 1;\n    background: #fafafa;\n    font-size: 13px;\n}\n.select2-container.select2-container--default .select2-selection--single .select2-selection__rendered {\n    line-height: 43px;\n    padding-left: 11px;\n    padding-right: 50px;\n    color: #222222;\n    text-transform: uppercase;\n}<\/style><div class='form-logic'>[[[[\"field36\",\"equal_to\",\"Sim\"]],[[\"show_fields\",\"field32\"]],\"and\"]]<\/div><div class=\"fc-pagination-cover fc-pagination-1\">\n\t\t\t\t<div class=\"fc-pagination width-100\">\n\t\t\t\t\t<div class=\"pagination-trigger \" data-index=\"0\">\n\t\t\t\t\t\t<span class=\"page-number\"><span >1<\/span><\/span>\n\t\t\t\t\t\t<span class=\"page-name \">Step 1<\/span>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t<style scoped=\"scoped\" >\n\t\t\t@media (max-width : 480px) {\n\t\t\t\t.fc_modal-dialog-1 .fc-pagination-cover .fc-pagination\n\t\t\t\t{\n\t\t\t\t\tbackground-color: transparent !important;\n\t\t\t\t}\n\t\t\t}\n\t\t\t\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .submit-cover .submit-button,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .fileupload-cover .button-file,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover .button,\n\t\t\t.formcraft-datepicker .ui-datepicker-header,\n\t\t\t.formcraft-datepicker .ui-datepicker-title\n\t\t\t{\n\t\t\t\tbackground: #d83135;\n\t\t\t\tcolor: #ffffff;\n\t\t\t}\n\t\t\t.formcraft-datepicker td .ui-state-active,\n\t\t\t.formcraft-datepicker td .ui-state-hover,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .slider-cover .ui-slider-range\n\t\t\t{\n\t\t\t\tbackground: #d83135;\n\t\t\t}\n\t\t\t#ui-datepicker-div.formcraft-datepicker .ui-datepicker-header,\n\t\t\t.formcraft-css .fc-form .field-cover>div.full hr\n\t\t\t{\n\t\t\t\tborder-color: #be2b2e;\n\t\t\t}\n\t\t\t#ui-datepicker-div.formcraft-datepicker .ui-datepicker-prev:hover,\n\t\t\t#ui-datepicker-div.formcraft-datepicker .ui-datepicker-next:hover,\n\t\t\t#ui-datepicker-div.formcraft-datepicker select.ui-datepicker-month:hover,\n\t\t\t#ui-datepicker-div.formcraft-datepicker select.ui-datepicker-year:hover\n\t\t\t{\n\t\t\t\tbackground-color: #be2b2e;\n\t\t\t}\n\t\t\t.formcraft-css .fc-pagination>div.active .page-number,\n\t\t\t.formcraft-css .form-cover-builder .fc-pagination>div:first-child .page-number\n\t\t\t{\n\t\t\t\tbackground-color: #d83135;\n\t\t\t\tcolor: #ffffff;\n\t\t\t}\n\t\t\t#ui-datepicker-div.formcraft-datepicker table.ui-datepicker-calendar th,\n\t\t\t#ui-datepicker-div.formcraft-datepicker table.ui-datepicker-calendar td.ui-datepicker-today a,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .star-cover label,\n\t\t\thtml .formcraft-css .fc-form.label-floating .form-element .field-cover.has-focus>span,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .customText-cover a,\n\t\t\t.formcraft-css .prev-next>div span:hover\n\t\t\t{\n\t\t\t\tcolor: #d83135;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .customText-cover a:hover\n\t\t\t{\n\t\t\t\tcolor: #be2b2e;\n\t\t\t}\n\t\t\thtml .formcraft-css .fc-form.fc-form-1.label-floating .form-element .field-cover > span\n\t\t\t{\n\t\t\t\tcolor: #666666;\n\t\t\t}\n\t\t\thtml .formcraft-css .fc-form .final-success .final-success-check {\n\t\t\t\tborder: 2px solid #666666;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"text\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"email\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"password\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"tel\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover textarea,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover select,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover .time-fields-cover,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover .awesomplete ul\n\t\t\t{\n\t\t\t\tcolor: #777;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"text\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"password\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"email\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"radio\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"checkbox\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"tel\"],\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover select,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover textarea\n\t\t\t{\n\t\t\t\tbackground-color: #fafafa;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"radio\"]:checked,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .field-cover input[type=\"checkbox\"]:checked {\n\t\t\t\tborder-color: #be2b2e;\n\t\t\t\tbackground: #d83135;\t\t\t\t\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .star-cover label .star\n\t\t\t{\n\t\t\t\ttext-shadow: 0px 1px 0px #be2b2e;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .slider-cover .ui-slider-range\n\t\t\t{\n\t\t\t\tbox-shadow: 0px 1px 1px #be2b2e inset;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .fileupload-cover .button-file\n\t\t\t{\n\t\t\t\tborder-color: #be2b2e;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .form-element-html input[type=\"password\"]:focus,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .form-element-html input[type=\"email\"]:focus,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .form-element-html input[type=\"tel\"]:focus,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .form-element-html input[type=\"text\"]:focus,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .form-element-html textarea:focus,\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .form-element-html select:focus\n\t\t\t{\n\t\t\t\tborder-color: #d83135;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1 .form-element .form-element-html .field-cover .is-read-only:focus {\n\t\t\t\tborder-color: #ccc;\n\t\t\t}\n\t\t\t.formcraft-css .fc-form.fc-form-1\t\t\t{\n\t\t\t\tfont-family: inherit;\n\t\t\t}\n\t\t\t@media (max-width : 480px) {\n\t\t\t\thtml .dedicated-page,\n\t\t\t\thtml .dedicated-page .formcraft-css .fc-pagination > div.active\n\t\t\t\t{\n\t\t\t\t\tbackground: transparent;\n\t\t\t\t}\n\t\t\t}\n\t\t<\/style>\n\t\t<div class=\"form-cover\">\n\t\t\t<form data-auto-scroll=\"\" data-no-message-redirect=\"\" data-thousand=\"\" data-decimal=\".\" data-delay=\"\" data-id=\"1\" class=\"fc-form fc-form-1 align- fc-temp-class spin- save-form- dont-submit-hidden- remove-asterisk- disable-enter- label-placeholder field-border-visible frame-visible icons-hide-false field-alignment-left\" style=\"width: 100%; color: #666666; font-size: 100%; background: transparent\">\n\t\t\t\t<div class=\"form-page form-page-0\" data-index=\"0\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"form-page-content     \">\n\t\t\t\t\t\t<div data-identifier=\"field41\" data-index=\"0\" style=\"width: 100%\" class=\" form-element form-element-field41 options- index- form-element-0 default-false form-element-type-heading is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><div style=\"background-color:\" class=\"heading-cover field-cover \"><div style=\"text-align: left; font-size: 1.5em; padding-top: ; padding-bottom: ; color:\" class=\"bold-\"><span >BRADESCO<\/span><\/div><input type=\"hidden\" data-field-id=\"field41\" name=\"field41[]\" value=\"BRADESCO\"><\/div><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field1\" data-index=\"1\" style=\"width: 50%\" class=\" even form-element form-element-field1 options- index- form-element-1 default-false form-element-type-oneLineText is-required-true -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >Nome para Contato<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"Nome para Contato\" make-read-only=\"\" data-field-id=\"field1\" name=\"field1[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"\" data-regexp=\"\" data-is-required=\"true\" data-allow-spaces=\"true\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-icon-user\">icon-user<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field37\" data-index=\"2\" style=\"width: 50%\" class=\" form-element form-element-field37 options- index- form-element-2 default-false form-element-type-dropdown is-required-true odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"dropdown-cover field-cover autocomplete-type- \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >Voc\u00ea possui?<\/span><\/span><span class=\"sub-label\"><span >pick one!<\/span><\/span><\/span><div><span class=\"error\"><\/span><select data-is-required=\"true\" class=\"validation-lenient\" data-field-id=\"field37\" name=\"field37\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"hover\" data-html=\"true\" data-original-title=\"\"><option value=\"\" class=\" \">Possui CNPJ?<\/option><option value=\"Sim\" class=\" \">Sim<\/option><option value=\"N\u00e3o\" class=\" \">N\u00e3o<\/option><\/select><input type=\"text\"><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field3\" data-index=\"3\" style=\"width: 100%\" class=\" even form-element form-element-field3 options- index- form-element-3 default-false form-element-type-email is-required-true -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"email-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >E-mail<\/span><\/span><span class=\"sub-label\"><span >a valid email<\/span><\/span><\/span><div><span class=\"error\"><\/span><input placeholder=\"E-mail\" data-field-id=\"field3\" type=\"text\" data-val-type=\"email\" make-read-only=\"\" data-is-required=\"true\" name=\"field3\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-original-title=\"\"><i class=\"formcraft-icon\">email<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field21\" data-index=\"4\" style=\"width: 50%\" class=\" form-element form-element-field21 options- index- form-element-4 default-false form-element-type-oneLineText is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >Telefone<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"Telefone\" make-read-only=\"\" data-field-id=\"field21\" name=\"field21[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-icon-phone\">icon-phone<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field42\" data-index=\"5\" style=\"width: 50%\" class=\" even form-element form-element-field42 options- index- form-element-5 default-false form-element-type-oneLineText is-required-false -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >Celular<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"Celular\" make-read-only=\"\" data-field-id=\"field42\" name=\"field42[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-icon-phone\">icon-phone<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field38\" data-index=\"6\" style=\"width: 70%\" class=\" form-element form-element-field38 options- index- form-element-6 default-false form-element-type-oneLineText is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >Cidade<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"Cidade\" make-read-only=\"\" data-field-id=\"field38\" name=\"field38[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"true\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field40\" data-index=\"7\" style=\"width: 30%\" class=\" even form-element form-element-field40 options- index- form-element-7 default-false form-element-type-dropdown is-required-false -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"dropdown-cover field-cover autocomplete-type- \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >Estado<\/span><\/span><span class=\"sub-label\"><span >pick one!<\/span><\/span><\/span><div><span class=\"error\"><\/span><select data-is-required=\"false\" class=\"validation-lenient\" data-field-id=\"field40\" name=\"field40\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"hover\" data-html=\"true\" data-original-title=\"\"><option value=\"\" class=\" \">Estado<\/option><option value=\"AC\" class=\" \">AC<\/option><option value=\"AL\" class=\" \">AL<\/option><option value=\"AP\" class=\" \">AP<\/option><option value=\"AM\" class=\" \">AM<\/option><option value=\"BA\" class=\" \">BA<\/option><option value=\"CE\" class=\" \">CE<\/option><option value=\"DF\" class=\" \">DF<\/option><option value=\"ES\" class=\" \">ES<\/option><option value=\"GO\" class=\" \">GO<\/option><option value=\"MA\" class=\" \">MA<\/option><option value=\"MT\" class=\" \">MT<\/option><option value=\"MS\" class=\" \">MS<\/option><option value=\"MG\" class=\" \">MG<\/option><option value=\"PA\" class=\" \">PA<\/option><option value=\"PB\" class=\" \">PB<\/option><option value=\"PR\" class=\" \">PR<\/option><option value=\"PE\" class=\" \">PE<\/option><option value=\"PI\" class=\" \">PI<\/option><option value=\"RJ\" class=\" \">RJ<\/option><option value=\"RN\" class=\" \">RN<\/option><option value=\"RS\" class=\" \">RS<\/option><option value=\"RO\" class=\" \">RO<\/option><option value=\"RR\" class=\" \">RR<\/option><option value=\"SC\" class=\" \">SC<\/option><option value=\"SP\" class=\" \">SP<\/option><option value=\"SE\" class=\" \">SE<\/option><option value=\"TO\" class=\" \">TO<\/option><\/select><input type=\"text\"><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field20\" data-index=\"8\" style=\"width: 100%\" class=\" form-element form-element-field20 options- index- form-element-8 default-false form-element-type-customText is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><div class=\"absolute-false customText-cover field-cover\" style=\"left: ; top: ;right: ;bottom: ;color: #666666 !important; background-color:\"><div class=\"full\" style=\"text-align: left\"><p style=\"text-align: center\" >Insira a quantidade de usu\u00e1rios dentro de cada <b>faixa et\u00e1ria <\/b>abaixo.<\/p><\/div><input type=\"hidden\" name=\"field20\" data-field-id=\"field20\"><\/div><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field5\" data-index=\"9\" style=\"width: 33%\" class=\" even form-element form-element-field5 options- index- form-element-9 default-false form-element-type-oneLineText is-required-false -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >00-18<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"00-18\" make-read-only=\"\" data-field-id=\"field5\" name=\"field5[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field9\" data-index=\"10\" style=\"width: 34%\" class=\" form-element form-element-field9 options- index- form-element-10 default-false form-element-type-oneLineText is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >19-23<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"19-23\" make-read-only=\"\" data-field-id=\"field9\" name=\"field9[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field12\" data-index=\"11\" style=\"width: 33%\" class=\" even form-element form-element-field12 options- index- form-element-11 default-false form-element-type-oneLineText is-required-false -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >24-28<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"24-28\" make-read-only=\"\" data-field-id=\"field12\" name=\"field12[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field11\" data-index=\"12\" style=\"width: 33%\" class=\" form-element form-element-field11 options- index- form-element-12 default-false form-element-type-oneLineText is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >29-33<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"29-33\" make-read-only=\"\" data-field-id=\"field11\" name=\"field11[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field10\" data-index=\"13\" style=\"width: 34%\" class=\" even form-element form-element-field10 options- index- form-element-13 default-false form-element-type-oneLineText is-required-false -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >34-38<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"34-38\" make-read-only=\"\" data-field-id=\"field10\" name=\"field10[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field13\" data-index=\"14\" style=\"width: 33%\" class=\" form-element form-element-field13 options- index- form-element-14 default-false form-element-type-oneLineText is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >39-43<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"39-43\" make-read-only=\"\" data-field-id=\"field13\" name=\"field13[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field15\" data-index=\"15\" style=\"width: 33%\" class=\" even form-element form-element-field15 options- index- form-element-15 default-false form-element-type-oneLineText is-required-false -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >44-48<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"44-48\" make-read-only=\"\" data-field-id=\"field15\" name=\"field15[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field14\" data-index=\"16\" style=\"width: 34%\" class=\" form-element form-element-field14 options- index- form-element-16 default-false form-element-type-oneLineText is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >49-53<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"49-53\" make-read-only=\"\" data-field-id=\"field14\" name=\"field14[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field8\" data-index=\"17\" style=\"width: 33%\" class=\" even form-element form-element-field8 options- index- form-element-17 default-false form-element-type-oneLineText is-required-false -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >54-58<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"54-58\" make-read-only=\"\" data-field-id=\"field8\" name=\"field8[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field7\" data-index=\"18\" style=\"width: 33%\" class=\" form-element form-element-field7 options- index- form-element-18 default-false form-element-type-oneLineText is-required-false odd -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><label class=\"oneLineText-cover field-cover \"><span class=\"sub-label-true\"><span class=\"main-label\"><span >59+<\/span><\/span><span class=\"sub-label\"><span >your full name<\/span><\/span><\/span><div><span class=\"error\"><\/span><input type=\"text\" placeholder=\"59+\" make-read-only=\"\" data-field-id=\"field7\" name=\"field7[]\" data-min-char=\"\" data-max-char=\"\" data-val-type=\"numbers\" data-regexp=\"\" data-is-required=\"false\" data-allow-spaces=\"\" class=\"validation-lenient\" data-placement=\"right\" data-toggle=\"tooltip\" tooltip=\"\" data-trigger=\"focus\" data-html=\"true\" data-input-mask=\"\" data-mask-placeholder=\"\" data-original-title=\"\"><i class=\"formcraft-icon formcraft-icon-type-no-icon\">no-icon<\/i><\/div><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div><div data-identifier=\"field4\" data-index=\"19\" style=\"width: 67%\" class=\" even form-element form-element-field4 options- index- form-element-19 default-false form-element-type-submit is-required-false -handle\">\n\t\t\t\t\t\t\t<div class=\"form-element-html\"><div ><div class=\"align-right wide-true submit-cover field-cover\"><button type=\"submit\" class=\"button submit-button\"><span class=\"text \">SOLICITAR OR\u00c7AMENTO<\/span><span class=\"spin-cover\"><i style=\"color:\" class=\"loading-icon icon-cog animate-spin\"><\/i><\/span><\/button><\/div><div class=\"submit-response \"><\/div><label ><input type=\"text\" class=\"required_field\" name=\"website\" autocomplete=\"maple-syrup-pot\"><\/label><\/div><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/form>\n\t\t\t<div class=\"prev-next prev-next-1\" style=\"width: 100%; color: #666666; font-size: 100%; background: transparent\">\n\t\t\t\t<div><label><input type=\"text\" class=\"  \"><\/label><span class=\"inactive page-prev \"><i class=\"formcraft-icon\">keyboard_arrow_left<\/i>Previous<\/span><\/div>\n\t\t\t\t<div><label><input type=\"text\" class=\"  \"><\/label><span class=\"page-next \">Next<i class=\"formcraft-icon\">keyboard_arrow_right<\/i><\/span><\/div>\n\t\t\t<\/div>\n\t\t<\/div><a class=\"powered-by\" target=\"_blank\" href=\"http:\/\/formcraft-wp.com?source=pb\"\/>FormCraft - WordPress form builder<\/a><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-371489828\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-371489828 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1919322730\">\n\n\t<div id=\"col-350083223\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-2103417903\">\n\n\t<div id=\"col-26879763\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2><span style=\"color: #a60707;\">Informa\u00e7\u00f5es Bradesco Sa\u00fade<\/span><\/h2>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\n  \n    <div class=\"row large-columns-4 medium-columns-1 small-columns-1 has-shadow row-box-shadow-2\">\n  \t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/bradesco-saude-telemedicina\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/02\/Telemedicina-Bradesco-Saude-300x169.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Telemedicina Bradesco Sa\u00fade\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/02\/Telemedicina-Bradesco-Saude-300x169.jpg 300w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/02\/Telemedicina-Bradesco-Saude-1024x576.jpg 1024w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/02\/Telemedicina-Bradesco-Saude-768x432.jpg 768w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/02\/Telemedicina-Bradesco-Saude-1536x864.jpg 1536w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/02\/Telemedicina-Bradesco-Saude.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Bradesco Sa\u00fade Telemedicina<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Atendimento m\u00e9dico por v\u00eddeo Benefici\u00e1rios Bradesco Sa\u00fade poder\u00e3o realizar consultas online em diversas especialidades m\u00e9dicas, [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/bradesco-saude-telemedicina\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tSaiba Mais\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">11<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">fev<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/como-escolher-plano-de-saude-bradesco\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/02\/Como-Escolher-Plano-de-Saude-Bradesco-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Como Escolher Plano de Sa\u00fade Bradesco\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/02\/Como-Escolher-Plano-de-Saude-Bradesco-300x200.jpg 300w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/02\/Como-Escolher-Plano-de-Saude-Bradesco.jpg 654w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Como Escolher Plano de Sa\u00fade Bradesco<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Veja como \u00e9 F\u00e1cil escolher qual Plano Bradesco Sa\u00fade contratar Voc\u00ea sabe como escolher um [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/como-escolher-plano-de-saude-bradesco\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tSaiba Mais\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">11<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">fev<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/meu-doutor-novamed-inaugura-novas-unidades\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"221\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/02\/Meu-Doutor-Novamed-inaugura-novas-unidades-300x221.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Meu Doutor Novamed inaugura novas unidades\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/02\/Meu-Doutor-Novamed-inaugura-novas-unidades-300x221.jpg 300w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/02\/Meu-Doutor-Novamed-inaugura-novas-unidades-1024x755.jpg 1024w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/02\/Meu-Doutor-Novamed-inaugura-novas-unidades-768x566.jpg 768w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/02\/Meu-Doutor-Novamed-inaugura-novas-unidades-1536x1133.jpg 1536w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/02\/Meu-Doutor-Novamed-inaugura-novas-unidades-2048x1510.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Meu Doutor Novamed inaugura  novas unidades<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Com a expans\u00e3o da rede de cl\u00ednicas de atendimento ao cliente a Bradesco Seguros comemora [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/meu-doutor-novamed-inaugura-novas-unidades\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tSaiba Mais\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">02<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">fev<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Bradesco-Saude-Reajuste-2020-300x169.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Bradesco Sa\u00fade Reajuste 2020\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Bradesco-Saude-Reajuste-2020-300x169.jpg 300w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Bradesco-Saude-Reajuste-2020-1024x576.jpg 1024w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Bradesco-Saude-Reajuste-2020-768x432.jpg 768w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Bradesco-Saude-Reajuste-2020-1536x864.jpg 1536w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Bradesco-Saude-Reajuste-2020.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Reajuste Bradesco Sa\u00fade &#8211; Covid 19<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Fim da suspens\u00e3o do reajuste 2020 Bradesco Sa\u00fade A Ag\u00eancia Nacional de Sa\u00fade Suplementar (ANS) [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tSaiba Mais\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">04<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">jan<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/informacoes-sobre-carencia-e-contratacao-bradesco-saude\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/Planos-Bradesco-Saude-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Planos Bradesco Sa\u00fade\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/Planos-Bradesco-Saude-300x200.jpg 300w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/Planos-Bradesco-Saude-768x512.jpg 768w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/Planos-Bradesco-Saude.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Informa\u00e7\u00f5es Sobre Car\u00eancia e Contrata\u00e7\u00e3o Bradesco Sa\u00fade<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Atendimento diferenciado, conforto e qualidade. A Bradesco Sa\u00fade oferece para seus clientes plano de sa\u00fade [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/informacoes-sobre-carencia-e-contratacao-bradesco-saude\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tSaiba Mais\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">17<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">dez<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/portal-do-programa-bradesco-saude\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"139\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/Bradesco-Saude-apresenta-novo-portal-do-programa-300x139.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Bradesco Sa\u00fade apresenta novo portal do programa\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/Bradesco-Saude-apresenta-novo-portal-do-programa-300x139.jpg 300w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/Bradesco-Saude-apresenta-novo-portal-do-programa-1024x475.jpg 1024w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/Bradesco-Saude-apresenta-novo-portal-do-programa-768x357.jpg 768w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/Bradesco-Saude-apresenta-novo-portal-do-programa.jpg 1400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Portal do Programa Bradesco Sa\u00fade<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Novo Portal do Programa Bradesco Sa\u00fade L\u00edder do mercado de sa\u00fade suplementar no Pa\u00eds, o [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/portal-do-programa-bradesco-saude\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tSaiba Mais\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">16<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">dez<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/bradesco-seguros-estao-no-ranking-do-premio-estadao-empresas-mais-pela-1a-vez\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"139\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/Premio-Estadao-300x139.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Premio Estad\u00e3o\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/Premio-Estadao-300x139.jpg 300w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/Premio-Estadao-1024x475.jpg 1024w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/Premio-Estadao-768x357.jpg 768w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/Premio-Estadao.jpg 1400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Bradesco Seguros est\u00e3o no ranking do pr\u00eamio Estad\u00e3o Empresas Mais pela 1\u00aa vez<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Pela oitava vez consecutiva, a Bradesco Sa\u00fade recebeu o pr\u00eamio Top of Mind Estad\u00e3o de [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/bradesco-seguros-estao-no-ranking-do-premio-estadao-empresas-mais-pela-1a-vez\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tSaiba Mais\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">16<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">dez<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/hospital-einstein-bradesco-saude\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/hospital-Einstein-300x199.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"hospital Einstein\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/hospital-Einstein-300x199.jpg 300w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/hospital-Einstein-768x509.jpg 768w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/12\/hospital-Einstein.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Hospital Einstein Bradesco Sa\u00fade<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Einstein, Bradesco Sa\u00fade firmam parceria e amplia atendimento aos pacientes por meio do Programa Meu [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/hospital-einstein-bradesco-saude\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tSaiba Mais\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">01<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">dez<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/bradesco-saude-lanca-videos-com-dicas-de-saude\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"122\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/09\/Bradesco-Sa\u00fade-lan\u00e7a-v\u00eddeos-300x122.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Bradesco Sa\u00fade lan\u00e7a v\u00eddeos\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/09\/Bradesco-Sa\u00fade-lan\u00e7a-v\u00eddeos-300x122.jpg 300w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/09\/Bradesco-Sa\u00fade-lan\u00e7a-v\u00eddeos-768x312.jpg 768w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/09\/Bradesco-Sa\u00fade-lan\u00e7a-v\u00eddeos.jpg 771w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Bradesco Sa\u00fade lan\u00e7a v\u00eddeos com dicas de sa\u00fade<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">S\u00e9rie de v\u00eddeos est\u00e1 dispon\u00edvel no canal YouTube da Bradesco Seguros e foi produzida para [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/bradesco-saude-lanca-videos-com-dicas-de-saude\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tSaiba Mais\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">30<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">set<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/promocao-bradesco-saude-03-a-13-de-setembro\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"161\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/05\/Plano-de-Sa\u00fade-Empresarial-300x161.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Plano de Sa\u00fade Empresarial\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/05\/Plano-de-Sa\u00fade-Empresarial-300x161.jpg 300w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/05\/Plano-de-Sa\u00fade-Empresarial-768x411.jpg 768w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/05\/Plano-de-Sa\u00fade-Empresarial.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Promo\u00e7\u00e3o Bradesco Sa\u00fade 03 a 13 de Setembro 2020<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Promo\u00e7\u00e3o Bradesco Sa\u00fade 03 a 13 de Setembro Saiba o valor do plano de Sa\u00fade [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/promocao-bradesco-saude-03-a-13-de-setembro\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tSaiba Mais\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">03<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">set<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/bradesco-saude-digital\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"146\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/07\/Bradesco-Sa\u00fade-digital-300x146.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Bradesco Sa\u00fade digital\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/07\/Bradesco-Sa\u00fade-digital-300x146.jpg 300w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/07\/Bradesco-Sa\u00fade-digital.jpg 512w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Bradesco Sa\u00fade Digital<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Bradesco Sa\u00fade Digital Coronav\u00edrus Para tirar d\u00favidas e falar com profissionais de sa\u00fade dedicados exclusivamente [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/bradesco-saude-digital\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tSaiba Mais\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">13<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">jul<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/cartilha-coronavirus\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"167\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/02\/Cartilha-sobre-Coronav\u00edrus-300x167.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Cartilha Coronav\u00edrus\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/02\/Cartilha-sobre-Coronav\u00edrus-300x167.jpg 300w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/02\/Cartilha-sobre-Coronav\u00edrus-768x428.jpg 768w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/02\/Cartilha-sobre-Coronav\u00edrus.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Cartilha Coronav\u00edrus<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">O que \u00e9 Coronav\u00edrus \u00c9 uma grande fam\u00edlia de v\u00edrus que recebeu esse nome por [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<button href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/cartilha-coronavirus\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\tSaiba Mais\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">05<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">fev<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-360098204\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-360098204 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" style=\"color:rgb(172, 0, 0);\">Aplicativo Plano de Sa\u00fade Bradesco<\/span><b><\/b><\/h3><\/div>\n<div class=\"row\"  id=\"row-1086050612\">\n\n\t<div id=\"col-819100551\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1548199683\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner box-shadow-3 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"445\" height=\"586\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2019\/04\/Aplicativo-plano-de-sa\u00fade-bradesco.jpg\" class=\"attachment-large size-large\" alt=\"Aplicativo plano de sa\u00fade bradesco\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2019\/04\/Aplicativo-plano-de-sa\u00fade-bradesco.jpg 445w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2019\/04\/Aplicativo-plano-de-sa\u00fade-bradesco-228x300.jpg 228w\" sizes=\"auto, (max-width: 445px) 100vw, 445px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1548199683 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1320500036\" class=\"col medium-8 small-12 large-8\"  >\n\t\t<div class=\"col-inner box-shadow-3\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 115%;\">Com o objetivo de sempre facilitar o dia a dia dos seus segurados, o Plano de Sa\u00fade Bradesco Confresa disponibilizou para download a vers\u00e3o atualizada do seu aplicativo Bradesco Sa\u00fade, oferecendo novas funcionalidades como, consultar reembolso, localizar referenciados, visualizar o cart\u00e3o de identifica\u00e7\u00e3o online \u2013 por interm\u00e9dio do aplicativo Carteira Digital, localizar farm\u00e1cias pr\u00f3ximas, 2\u00aa via do extrato de IR, al\u00e9m de criar a carteira de vacina\u00e7\u00e3o e acessar o calend\u00e1rio de vacinas.<\/span><\/p>\n<p><span style=\"font-size: 115%;\">Para utilizar o aplicativo, o benefici\u00e1rio precisa baix\u00e1-lo por meio do Google Play (plataforma Android) ou a App Store (iOS) de seu smartfone.<\/span><\/p>\n\t<div id=\"gap-406158436\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-406158436 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1132469315\">\n\n\t<div id=\"col-608546814\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1570487684\">\n\t\t<a class=\"\" href=\"https:\/\/itunes.apple.com\/br\/app\/bradesco-seguros\/id1256508403?mt=8\" target=\"_blank\" rel=\"noopener noreferrer\" >\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"191\" height=\"64\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2019\/04\/aplicativo-store-Bradesco-Seguros.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1570487684 {\n  width: 64%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-728997582\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_536084130\">\n\t\t<a class=\"\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=br.com.bradseg.bscelular\" target=\"_blank\" rel=\"noopener noreferrer\" >\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"210\" height=\"61\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2019\/04\/aplicativo-google-play-bradesco-seguros.jpg\" class=\"attachment-large size-large\" alt=\"aplicativo google play bradesco seguros\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_536084130 {\n  width: 73%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\n<style>\n#col-1320500036 > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-142724272\">\n\n\t<div id=\"col-559397971\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<figure id=\"attachment_6931\" aria-describedby=\"caption-attachment-6931\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-6931\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/03\/Plano-de-Sa\u00fade-Bradesco-300x96.png\" alt=\"Plano de Sa\u00fade Bradesco\" width=\"300\" height=\"96\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/03\/Plano-de-Sa\u00fade-Bradesco-300x96.png 300w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2020\/03\/Plano-de-Sa\u00fade-Bradesco.png 512w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-6931\" class=\"wp-caption-text\">Plano de Sa\u00fade Bradesco<\/figcaption><\/figure>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-6921","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plano de Sa\u00fade Bradesco com At\u00e9 50% Desconto<\/title>\n<meta name=\"description\" content=\"Plano de Sa\u00fade Bradesco Individual, Plano de Sa\u00fade Bradesco Empresarial, Plano de Sa\u00fade Bradesco MEi, com uma exelente rede de hospitais em todo Brasil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-de-saude-bradesco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plano de Sa\u00fade Bradesco com At\u00e9 50% Desconto\" \/>\n<meta property=\"og:description\" content=\"Plano de Sa\u00fade Bradesco Individual, Plano de Sa\u00fade Bradesco Empresarial, Plano de Sa\u00fade Bradesco MEi, com uma exelente rede de hospitais em todo Brasil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-de-saude-bradesco\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-22T01:11:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"23 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-de-saude-bradesco\/\",\"url\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-de-saude-bradesco\/\",\"name\":\"Plano de Sa\u00fade Bradesco com At\u00e9 50% Desconto\",\"isPartOf\":{\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#website\"},\"datePublished\":\"2020-03-16T23:15:30+00:00\",\"dateModified\":\"2020-03-22T01:11:24+00:00\",\"description\":\"Plano de Sa\u00fade Bradesco Individual, Plano de Sa\u00fade Bradesco Empresarial, Plano de Sa\u00fade Bradesco MEi, com uma exelente rede de hospitais em todo Brasil.\",\"breadcrumb\":{\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-de-saude-bradesco\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-de-saude-bradesco\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-de-saude-bradesco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plano de Sa\u00fade Bradesco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#website\",\"url\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/\",\"name\":\"\",\"description\":\"Plano com 50% Desconto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plano de Sa\u00fade Bradesco com At\u00e9 50% Desconto","description":"Plano de Sa\u00fade Bradesco Individual, Plano de Sa\u00fade Bradesco Empresarial, Plano de Sa\u00fade Bradesco MEi, com uma exelente rede de hospitais em todo Brasil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-de-saude-bradesco\/","og_locale":"pt_BR","og_type":"article","og_title":"Plano de Sa\u00fade Bradesco com At\u00e9 50% Desconto","og_description":"Plano de Sa\u00fade Bradesco Individual, Plano de Sa\u00fade Bradesco Empresarial, Plano de Sa\u00fade Bradesco MEi, com uma exelente rede de hospitais em todo Brasil.","og_url":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-de-saude-bradesco\/","article_modified_time":"2020-03-22T01:11:24+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"23 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-de-saude-bradesco\/","url":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-de-saude-bradesco\/","name":"Plano de Sa\u00fade Bradesco com At\u00e9 50% Desconto","isPartOf":{"@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#website"},"datePublished":"2020-03-16T23:15:30+00:00","dateModified":"2020-03-22T01:11:24+00:00","description":"Plano de Sa\u00fade Bradesco Individual, Plano de Sa\u00fade Bradesco Empresarial, Plano de Sa\u00fade Bradesco MEi, com uma exelente rede de hospitais em todo Brasil.","breadcrumb":{"@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-de-saude-bradesco\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-de-saude-bradesco\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/plano-de-saude-bradesco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/"},{"@type":"ListItem","position":2,"name":"Plano de Sa\u00fade Bradesco"}]},{"@type":"WebSite","@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#website","url":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/","name":"","description":"Plano com 50% Desconto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/pages\/6921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/comments?post=6921"}],"version-history":[{"count":16,"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/pages\/6921\/revisions"}],"predecessor-version":[{"id":6961,"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/pages\/6921\/revisions\/6961"}],"wp:attachment":[{"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/media?parent=6921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}