{"id":7481,"date":"2021-01-04T10:33:12","date_gmt":"2021-01-04T13:33:12","guid":{"rendered":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/?p=7481"},"modified":"2021-04-22T08:21:32","modified_gmt":"2021-04-22T11:21:32","slug":"reajuste-bradesco-saude-covid-19","status":"publish","type":"post","link":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/","title":{"rendered":"Reajuste Bradesco Sa\u00fade &#8211; Covid 19"},"content":{"rendered":"<h1>Fim da suspens\u00e3o do reajuste 2020 Bradesco Sa\u00fade<\/h1>\n<p>A Ag\u00eancia Nacional de Sa\u00fade Suplementar (ANS) determinou que o valor das mensalidades, a partir de janeiro de 2021, A <a href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/\" target=\"_blank\" rel=\"noopener noreferrer\">Bradesco Sa\u00fade<\/a> voltar\u00e1 a considerar os reajustes que foram suspensos em 2020, seguindo determina\u00e7\u00e3o do Comunicado n\u00ba 85 da ANS, de 31 de agosto de 2020.<\/p>\n<p>Os valores da recomposi\u00e7\u00e3o do que deixou de ser cobrado durante o ano de 2020 ser\u00e3o dilu\u00eddos em 12 parcelas iguais, que constar\u00e3o dos boletos de janeiro a dezembro de 2021, conforme Comunicado n\u00ba 87, da ANS, de 27 de novembro de 2020.<\/p>\n<p>&nbsp;<\/p>\n<h2>Veja abaixo a condi\u00e7\u00e3o dos planos SPG com at\u00e9 29 vidas:<\/h2>\n<p>Reajuste anual: para os contratos com anivers\u00e1rio entre maio e agosto de 2020, a parcela referente ao percentual de reajuste n\u00e3o ser\u00e1 cobrada nos meses de setembro a dezembro do ano de 2020, per\u00edodo no qual a mensalidade voltar\u00e1 a ter o valor vigente antes do reajuste. Os contratos com anivers\u00e1rio entre setembro e dezembro n\u00e3o ter\u00e3o o percentual de reajuste aplicado em 2020.<\/p>\n<p>Sobre os boletos de 2020: o boleto de setembro j\u00e1 havia sido processado quando da decis\u00e3o da ANS, assim, seguindo a orienta\u00e7\u00e3o da ANS, os valores de reajuste que deveriam ser descontados nesse m\u00eas ser\u00e3o compensados (devolvidos) no boleto de outubro.<\/p>\n<p>Sobre os boletos de 2021: a partir de janeiro de 2021, os boletos voltar\u00e3o aos valores atualizados com os reajustes por mudan\u00e7a de faixa et\u00e1ria e reajuste anual, e a recomposi\u00e7\u00e3o dos valores n\u00e3o cobrados em 2020 ser\u00e1 realizada ao longo de 2021, respeitando-se o contrato e a retroatividade permitida pela ANS.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"row-2117137398\" class=\"row\">\n<div id=\"col-1215888178\" class=\"col small-12 large-12\">\n<div class=\"col-inner\">\n<h2>Central de Atendimento SPG Bradesco Sa\u00fade:<\/h2>\n<p>Estrutura de p\u00f3s-venda para suporte aos Corretores e Clientes, com equipes destinadas a prestar atendimento \u00e0 \u00e1rea de Recursos Humanos, proporcionando informa\u00e7\u00f5es necess\u00e1rias e auxiliando os gestores no acompanhamento dos processos que envolvam a utiliza\u00e7\u00e3o do plano de sa\u00fade.<br \/>\n<strong><i class=\"fa fa-check-square-o fa- \"><\/i>\u00a04004 2761 (capitais e regi\u00f5es metropolitanas)<\/strong><br \/>\n<strong><i class=\"fa fa-check-square-o fa- \"><\/i>\u00a00800 701 2761 (demais localidades)<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"row-1262073722\" class=\"row\">\n<div id=\"col-377930974\" class=\"col small-12 large-12\">\n<div class=\"col-inner\">\n<div id=\"gap-548092435\" class=\"gap-element clearfix\"><\/div>\n<h2>CRC \u2013 Central de Relacionamento com Cliente Bradesco Sa\u00fade:<\/h2>\n<p>Linha de telefone especial para contato, de forma simples e r\u00e1pida, com a Operadora. Dispon\u00edvel 24 horas por dia, 7 dias por semana. Nesse canal, o Cliente pode esclarecer suas d\u00favidas e obter informa\u00e7\u00f5es sobre coberturas, c\u00e1lculo pr\u00e9vio e acompanhamento de reembolso, al\u00e9m de informa\u00e7\u00f5es sobre a Rede Referenciada, entre outras.<br \/>\n<strong><i class=\"fa fa-check-square-o fa- \"><\/i>\u00a04004 2700 (capitais e regi\u00f5es metropolitanas)<\/strong><br \/>\n<strong><i class=\"fa fa-check-square-o fa- \"><\/i>\u00a00800 701 2700 (demais localidades)<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7482\" src=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Reajuste-Bradesco-Saude-300x169.jpg\" alt=\"Reajuste Bradesco Sa\u00fade\" width=\"350\" height=\"197\" srcset=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Reajuste-Bradesco-Saude-300x169.jpg 300w, https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Reajuste-Bradesco-Saude.jpg 512w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"row-1694767360\" class=\"row\">\n<div id=\"col-2009828068\" class=\"col small-12 large-12\">\n<div class=\"col-inner\">\n<div id=\"gap-1873548989\" class=\"gap-element clearfix\"><\/div>\n<h2>Servi\u00e7o de Atendimento ao Consumidor Bradesco Sa\u00fade:<\/h2>\n<p>Servi\u00e7o telef\u00f4nico gratuito, dispon\u00edvel todos os dias, ininterruptamente, para resolu\u00e7\u00e3o de problemas na rela\u00e7\u00e3o de consumo, por meio do fornecimento de informa\u00e7\u00f5es p\u00fablicas e de recebimento de reclama\u00e7\u00f5es de todos os produtos e servi\u00e7os comercializados. S\u00e3o informa\u00e7\u00f5es p\u00fablicas aquelas de car\u00e1ter institucional do Grupo Bradesco Seguros, endere\u00e7os e telefones de Sucursais, Corretores e prestadores de servi\u00e7os vinculados ao neg\u00f3cio, hor\u00e1rios de funcionamento das Sucursais e canais de atendimento, endere\u00e7os de sites do Grupo Bradesco Seguros, dentre outras.<br \/>\n<strong><i class=\"fa fa-check-square-o fa- \"><\/i>\u00a00800 727 9966<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fim da suspens\u00e3o do reajuste 2020 Bradesco Sa\u00fade A Ag\u00eancia Nacional de Sa\u00fade Suplementar (ANS) determinou que o valor das mensalidades, a partir de janeiro de 2021, A Bradesco Sa\u00fade voltar\u00e1 a considerar os reajustes que foram suspensos em 2020, seguindo determina\u00e7\u00e3o do Comunicado n\u00ba 85 da ANS, de 31 de agosto de 2020. Os [&#8230;]\n","protected":false},"author":1,"featured_media":7484,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[12],"class_list":["post-7481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-bradesco-saude","tag-reajuste-bradesco-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reajuste Bradesco Sa\u00fade - Covid 19 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reajuste Bradesco Sa\u00fade - Covid 19 -\" \/>\n<meta property=\"og:description\" content=\"Fim da suspens\u00e3o do reajuste 2020 Bradesco Sa\u00fade A Ag\u00eancia Nacional de Sa\u00fade Suplementar (ANS) determinou que o valor das mensalidades, a partir de janeiro de 2021, A Bradesco Sa\u00fade voltar\u00e1 a considerar os reajustes que foram suspensos em 2020, seguindo determina\u00e7\u00e3o do Comunicado n\u00ba 85 da ANS, de 31 de agosto de 2020. Os [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-04T13:33:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-22T11:21:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Bradesco-Saude-Reajuste-2020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bradesco Saude\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bradesco Saude\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/\",\"url\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/\",\"name\":\"Reajuste Bradesco Sa\u00fade - Covid 19 -\",\"isPartOf\":{\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Bradesco-Saude-Reajuste-2020.jpg\",\"datePublished\":\"2021-01-04T13:33:12+00:00\",\"dateModified\":\"2021-04-22T11:21:32+00:00\",\"author\":{\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#\/schema\/person\/4b8ff967e21a341f03d75a544e7aceb8\"},\"breadcrumb\":{\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/#primaryimage\",\"url\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Bradesco-Saude-Reajuste-2020.jpg\",\"contentUrl\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Bradesco-Saude-Reajuste-2020.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Bradesco Sa\u00fade Reajuste 2020\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reajuste Bradesco Sa\u00fade &#8211; Covid 19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#website\",\"url\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/\",\"name\":\"\",\"description\":\"Plano com 50% Desconto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#\/schema\/person\/4b8ff967e21a341f03d75a544e7aceb8\",\"name\":\"Bradesco Saude\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2616aed5f2267b566369bcad98cf1c87?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2616aed5f2267b566369bcad98cf1c87?s=96&d=mm&r=g\",\"caption\":\"Bradesco Saude\"},\"url\":\"https:\/\/planodesaudebr.com.br\/bradesco-saude\/author\/bradesco-saude\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reajuste Bradesco Sa\u00fade - Covid 19 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/","og_locale":"pt_BR","og_type":"article","og_title":"Reajuste Bradesco Sa\u00fade - Covid 19 -","og_description":"Fim da suspens\u00e3o do reajuste 2020 Bradesco Sa\u00fade A Ag\u00eancia Nacional de Sa\u00fade Suplementar (ANS) determinou que o valor das mensalidades, a partir de janeiro de 2021, A Bradesco Sa\u00fade voltar\u00e1 a considerar os reajustes que foram suspensos em 2020, seguindo determina\u00e7\u00e3o do Comunicado n\u00ba 85 da ANS, de 31 de agosto de 2020. Os [...]","og_url":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/","article_published_time":"2021-01-04T13:33:12+00:00","article_modified_time":"2021-04-22T11:21:32+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Bradesco-Saude-Reajuste-2020.jpg","type":"image\/jpeg"}],"author":"Bradesco Saude","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Bradesco Saude","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/","url":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/","name":"Reajuste Bradesco Sa\u00fade - Covid 19 -","isPartOf":{"@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Bradesco-Saude-Reajuste-2020.jpg","datePublished":"2021-01-04T13:33:12+00:00","dateModified":"2021-04-22T11:21:32+00:00","author":{"@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#\/schema\/person\/4b8ff967e21a341f03d75a544e7aceb8"},"breadcrumb":{"@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/#primaryimage","url":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Bradesco-Saude-Reajuste-2020.jpg","contentUrl":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-content\/uploads\/2021\/01\/Bradesco-Saude-Reajuste-2020.jpg","width":1920,"height":1080,"caption":"Bradesco Sa\u00fade Reajuste 2020"},{"@type":"BreadcrumbList","@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/reajuste-bradesco-saude-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/"},{"@type":"ListItem","position":2,"name":"Reajuste Bradesco Sa\u00fade &#8211; Covid 19"}]},{"@type":"WebSite","@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#website","url":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/","name":"","description":"Plano com 50% Desconto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#\/schema\/person\/4b8ff967e21a341f03d75a544e7aceb8","name":"Bradesco Saude","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2616aed5f2267b566369bcad98cf1c87?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2616aed5f2267b566369bcad98cf1c87?s=96&d=mm&r=g","caption":"Bradesco Saude"},"url":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/author\/bradesco-saude\/"}]}},"_links":{"self":[{"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/posts\/7481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/comments?post=7481"}],"version-history":[{"count":5,"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/posts\/7481\/revisions"}],"predecessor-version":[{"id":7565,"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/posts\/7481\/revisions\/7565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/media\/7484"}],"wp:attachment":[{"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/media?parent=7481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/categories?post=7481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/planodesaudebr.com.br\/bradesco-saude\/wp-json\/wp\/v2\/tags?post=7481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}